{"id":4364,"date":"2021-09-24T20:06:41","date_gmt":"2021-09-24T18:06:41","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?page_id=4364"},"modified":"2024-06-28T11:59:17","modified_gmt":"2024-06-28T09:59:17","slug":"minecraft-verzauberungen","status":"publish","type":"page","link":"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/","title":{"rendered":"Minecraft Verzauberungen Anleitung"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"546\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/verzauberung-minecraft-1024x546.jpg\" alt=\"Minecraft Verzauberungen Leitfaden\" class=\"wp-image-4365\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/verzauberung-minecraft-1024x546.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/verzauberung-minecraft-300x160.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/verzauberung-minecraft-768x410.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/verzauberung-minecraft.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Die Verzauberung in Minecraft zeichnet sich dadurch aus, dass Werkzeuge, Waffen, B\u00fccher, R\u00fcstungen und einige andere Gegenst\u00e4nde \u00fcber den Verzauberungstisch verzaubert werden. Du gibst Erfahrungspunkte aus, um die Eigenschaften des verzauberten Gegenstands zu verbessern oder ihm etwas hinzuzuf\u00fcgen, um ihn zu verbessern.<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/minecraft-enchanting-table.png\" alt=\"minecraft enchanting table\" class=\"wp-image-4325\" width=\"131\" height=\"131\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/minecraft-enchanting-table.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/minecraft-enchanting-table-150x150.png 150w\" sizes=\"auto, (max-width: 131px) 100vw, 131px\" \/><\/figure><\/div>\n\n\n<p>Since the official release of the game in November 2011, Minecraft has had a lot of Seit der offiziellen Ver\u00f6ffentlichung des Spiels im November 2011 gab es in Minecraft viele gro\u00dfe Ver\u00e4nderungen. Eine der wichtigsten davon ist die M\u00f6glichkeit, deine Ausr\u00fcstung zu verzaubern. Der folgende kurze Leitfaden f\u00fchrt dich in diese Neuerung ein und erkl\u00e4rt sie dir vor allem, damit du die Kunst der Verzauberung beherrschst.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a9896cb1b636\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9896cb1b636\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Die-notwendige-Ausruestung\" >Die notwendige Ausr\u00fcstung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Methoden-der-Verzauberung\" >Methoden der Verzauberung<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Verwendung-des-Zaubertisches\" >Verwendung des Zaubertisches<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Aendern-der-verfuegbaren-Verzauberungen\" >\u00c4ndern der verf\u00fcgbaren Verzauberungen<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Mit-dem-Amboss-Verzauberungen-kombinieren\" >Mit dem Amboss Verzauberungen kombinieren<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Ein-verzaubertes-Buch-benutzen\" >Ein verzaubertes Buch benutzen<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Entzaubern-eines-Objekts\" >Entzaubern eines Objekts<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-verzauberungen\/#Liste-der-Verzauberungen\" >Liste der Verzauberungen<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Die-notwendige-Ausruestung\"><\/span>Die notwendige Ausr\u00fcstung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Um Ihre Ausr\u00fcstung zu verzaubern, ben\u00f6tigen Sie die folgenden Gegenst\u00e4nde:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/table-enchantment-library-minecraft.jpg\" alt=\"minecraft enchanting table in library\" class=\"wp-image-4331\" width=\"300\" height=\"213\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/table-enchantment-library-minecraft.jpg 600w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/table-enchantment-library-minecraft-300x213.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Ein zauberhafter Tisch in einer Bibliothek<\/figcaption><\/figure><\/div>\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-zaubertisch-wie-man-ihn-herstellt-aufstellt-und-benutzt\/\">zaubertisch<\/a>: wird zur Verzauberung von Gegenst\u00e4nden verwendet und ist somit ein wichtiger Baustein f\u00fcr die Verzauberung.<\/li>\n\n\n\n<li>Bibliothek: Jede Bibliothek erh\u00f6ht die Stufe der Verzauberungen.<\/li>\n\n\n\n<li>Lapislazuli: wird ben\u00f6tigt, um den Tisch zu f\u00fcllen.<\/li>\n\n\n\n<li>Buch: Man kann ein Buch verzaubern und die Verzauberung dann mit Hilfe eines Ambosses auf einen anderen Gegenstand anwenden.<\/li>\n<\/ul>\n\n\n\n<p>Sie k\u00f6nnen leicht Bibliotheken dank der D\u00f6rfer machen, m\u00fcssen Sie Mine Lapislazuli zu finden und Sie finden B\u00fccher in den D\u00f6rfern. Wenn du nicht wei\u00dft, wie man einen zaubertischen Tisch baut, kannst du die folgenden Schritte befolgen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Methoden-der-Verzauberung\"><\/span>Methoden der Verzauberung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es gibt drei M\u00f6glichkeiten, einen Gegenstand im \u00dcberlebensmodus zu verzaubern:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00dcber einen Verzauberungstisch im Austausch gegen Erfahrungspunkte und Lapislazuli. Nur unverzauberte Gegenst\u00e4nde k\u00f6nnen auf diese Weise verzaubert werden.<\/li>\n\n\n\n<li>\u00dcber einen <a href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-und-benutzt-man-einen-amboss-in-minecraft\/\">Amboss<\/a>, indem man ein verzaubertes Buch mit einem Gegenstand kombiniert.<\/li>\n\n\n\n<li>\u00dcber einen Amboss, indem man zwei Gegenst\u00e4nde desselben Typs mit unterschiedlichen Verzauberungen zu einem Gegenstand kombiniert, der die Verzauberungen beider besitzt.<\/li>\n<\/ul>\n\n\n\n<p>Ein Spieler kann auch bereits verzauberte Gegenst\u00e4nde erhalten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/minecraft-tutos.com\/de\/wie-kann-man-handel-und-austausch-mit-den-dorfbewohnern-in-minecraft-betreiben\/\">\u00dcber einen Dorfbewohner,<\/a> der bestimmte verzauberte Gegenst\u00e4nde gegen Smaragde eintauschen kann.<\/li>\n\n\n\n<li>Durch das Fischen, das die M\u00f6glichkeit bietet, verzauberte Gegenst\u00e4nde zu erhalten.<\/li>\n\n\n\n<li>Durch einen Zombie, einen Ertrinkenden, einen mumifizierten Zombie, ein Skelett usw.: Wenn sie verzauberte Gegenst\u00e4nde haben und der Spieler sie t\u00f6tet, hat er eine 8,5%ige Chance, jeden dieser Gegenst\u00e4nde fallen zu lassen.<\/li>\n\n\n\n<li>Durch die Entdeckung dieser Gegenst\u00e4nde in Endst\u00e4dten und anderen verschiedenen Schatztruhen, wie z.B. Wracks, Minensch\u00e4chten, Verlie\u00dfen, W\u00fcstentempeln, Dschungeltempeln, Waldvillen, Meeresruinen und Festungen.<\/li>\n\n\n\n<li>T\u00f6ten Sie R\u00e4uber und R\u00e4cher in Raubz\u00fcgen.<\/li>\n<\/ul>\n\n\n\n<p>Serverbetreiber und Spieler in Einzelspielerwelten, in denen Cheats erlaubt sind, k\u00f6nnen Gegenst\u00e4nde auch mit Befehlen wie <em>\/enchant<\/em> verzaubern. Bei der Verzauberung mit dem Befehl \/give betr\u00e4gt die maximale Verzauberungsstufe 2.147.483.647. Im Kreativmodus k\u00f6nnen Gegenst\u00e4nde \u00fcber Amboss und verzauberte B\u00fccher verzaubert werden, ohne dass Erfahrungspunkte ben\u00f6tigt werden. Verzauberte B\u00fccher sind im Inventar des Kreativmodus verf\u00fcgbar, wobei einzelne Buchanzeigen f\u00fcr die h\u00f6chste Stufe jeder Verzauberung und andere Stufen \u00fcber die Registerkarte &#8220;Suchen&#8221; verf\u00fcgbar sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Verwendung-des-Zaubertisches\"><\/span>Verwendung des Zaubertisches<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ein Gegenstand kann verzaubert werden, indem man einen Zaubertisch verwendet und den Gegenstand in die Eingabefelder und 1-3 Lapislazuli in das daf\u00fcr vorgesehene Feld legt. Sobald der Gegenstand platziert ist, erscheinen drei (pseudo-)zuf\u00e4llige Optionen auf der rechten Seite der Benutzeroberfl\u00e4che. Die Glyphen hier haben keinen Einfluss auf die Verzauberung, aber wenn man mit dem Mauszeiger \u00fcber eine angezeigte Verzauberung f\u00e4hrt, wird eine anzuwendende Verzauberung angezeigt (auf mobilen Ger\u00e4ten kann der Spieler auf eine Verzauberung tippen, bevor er den Lapislazuli platziert, oder die Verzauberung halten, bevor er sie losl\u00e4sst). Die einzige verf\u00fcgbare Auswahl hat eine Stufenanforderung, die gleich oder kleiner ist als die aktuelle Stufe des Spielers, und eine Lapislazuli-Anforderung, die gleich oder kleiner ist als die Anzahl der auf dem Tisch platzierten Lapislazuli.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/interface-enchanting-table-empty.jpg\" alt=\"minecraft enchanting table interface\" class=\"wp-image-4337\" width=\"300\" height=\"213\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/interface-enchanting-table-empty.jpg 600w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/interface-enchanting-table-empty-300x213.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Die Schnittstelle des Zaubertisches.<\/figcaption><\/figure><\/div>\n\n\n<p>Jede Option verf\u00fcgt \u00fcber eine Reihe von zuf\u00e4lligen Verzauberungen, die von der Anzahl der erforderlichen Erfahrungsstufen abh\u00e4ngen (eine Verzauberung der Stufe 10 kann einem Deck beispielsweise die Verzauberung &#8220;Effizienz II&#8221; verleihen); die tats\u00e4chlichen Kosten der Stufe und die Anzahl der ben\u00f6tigten Lapislazuli haben keinen Einfluss.<\/p>\n\n\n\n<p>Obwohl der Spieler mindestens die erforderliche Stufe haben muss, um eine Verzauberung zu erhalten, ist die Anzahl der Stufen, die er zahlen muss, dieselbe wie die Anzahl der ben\u00f6tigten Lapislazuli. Wenn zum Beispiel die dritte aufgef\u00fchrte Verzauberung eine Verzauberung der Stufen 30-50 ist, muss der Spieler mindestens 30 Stufen haben, zahlt aber nur 3 Stufen und 3 Lapislazuli.<\/p>\n\n\n\n<p>Die Stufenanforderung beeinflusst die Menge, die Art und die Stufe der Verzauberungen, die dem Gegenstand verliehen werden, wobei h\u00f6here Erfahrungsstufen im Allgemeinen zu mehr und\/oder h\u00f6herstufigen Verzauberungen f\u00fchren. Dennoch gibt es einen betr\u00e4chtlichen Zufallsfaktor, und selbst eine Verzauberung der Stufe 30 (das Maximum) garantiert nicht mehr als eine Verzauberung oder sogar, dass die Verzauberungen &#8220;maximal stark&#8221; sind &#8211; eine Verzauberung der Stufe 30 kann zum Beispiel immer noch nur Fortune II oder Effizienz III verleihen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-object-with-enchanting-table.jpg\" alt=\"enchanting diamond pickaxe minecraft\" class=\"wp-image-4341\" width=\"300\" height=\"213\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-object-with-enchanting-table.jpg 600w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-object-with-enchanting-table-300x213.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Eine Diamantspitzhacke wird verzaubert.<\/figcaption><\/figure><\/div>\n\n\n<p>Um die Stufe der Verzauberung zu erh\u00f6hen, m\u00fcssen die Regale neben dem Zaubertisch platziert werden, wobei ein Luftblock dazwischen liegen muss. Um die oben genannten Verzauberungen der Stufe 30 zu erreichen, m\u00fcssen insgesamt 15 Regale um den Zaubertisch herum aufgestellt werden. Weitere Informationen zu diesem Thema finden Sie auf der Seite \u00fcber die Verzauberungsmechanik.<\/p>\n\n\n\n<p>Die Verzauberung eines Buches erzeugt ein verzaubertes Buch, das selbst nichts bewirkt, sondern die Verzauberung f\u00fcr eine sp\u00e4tere Anwendung auf einen anderen Gegenstand mit einem Amboss &#8220;speichert&#8221;.<\/p>\n\n\n\n<p>Anders als der Amboss kostet die Verwendung des Zaubertisches im Kreativmodus Erfahrung. Wenn der Spieler jedoch nicht genug Erfahrung hat, sinkt die Erfahrung auf Null und die Verzauberung funktioniert trotzdem, auch wenn er den Zaubertisch benutzt, w\u00e4hrend er bereits auf Stufe Null ist.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Aendern-der-verfuegbaren-Verzauberungen\"><\/span>\u00c4ndern der verf\u00fcgbaren Verzauberungen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Die Verzauberung eines Gegenstandes auf einer beliebigen Verzauberungsstufe ver\u00e4ndert den Verzauberungs-Samen des Spielers, wodurch sich die m\u00f6glichen Verzauberungen f\u00fcr jeden Gegenstand auf jeder Verzauberungsstufe \u00e4ndern. Wenn also keine der verf\u00fcgbaren Verzauberungen f\u00fcr ein Werkzeug gew\u00fcnscht wird, k\u00f6nnen 1 Lapislazuli und 1 Stufe ausgegeben werden, um ein anderes Buch oder Werkzeug zu verzaubern, um die Liste zu aktualisieren.<\/p>\n\n\n\n<p>Die m\u00f6glichen Verzauberungen h\u00e4ngen vom Verzauberungs-Samen des Spielers, der Art des Gegenstands und des Materials sowie der Verzauberungsstufe (1-30) ab. Das Entfernen und Wiedereinsetzen des Gegenstandes, das Anklicken eines anderen Gegenstandes, das Verwenden eines anderen Gegenstandes derselben Art und desselben Materials, das Ersetzen oder Verschieben des Tisches (unter Beibehaltung der gleichen Anzahl von B\u00fccherregalen), das Verwenden eines anderen Tisches mit der gleichen Anzahl von B\u00fccherregalen oder das Ersetzen oder Umstellen der B\u00fccherregale, ohne deren Gesamtzahl zu ver\u00e4ndern, hat keinen Einfluss auf die m\u00f6glichen Verzauberungen.<\/p>\n\n\n\n<p>Das \u00c4ndern der angebotenen Verzauberungsstufen durch Hinzuf\u00fcgen, L\u00f6schen oder Sperren von Bibliotheken \u00e4ndert die angezeigten Verzauberungen, aber nicht die m\u00f6glichen Verzauberungen; die Verwendung einer anderen Verzauberungstabelle mit der vorherigen Bibliotheksnummer beh\u00e4lt die vorherigen Verzauberungen bei. Die Verzauberungen f\u00fcr eine bestimmte Verzauberungsstufe (mit demselben Saatgut und Gegenstand) unterscheiden sich auch je nach der Reihe, in der sie erscheinen, aber sie sind nicht &#8220;besser&#8221; oder &#8220;schlechter&#8221; je nach Reihe, trotz der unterschiedlichen Ressourcenkosten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mit-dem-Amboss-Verzauberungen-kombinieren\"><\/span>Mit dem Amboss Verzauberungen kombinieren<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ein Amboss kann verwendet werden, um die Verzauberungen zweier Gegenst\u00e4nde zu kombinieren, wobei der eine geopfert und der andere repariert wird. Die Gegenst\u00e4nde m\u00fcssen kompatibel sein; sie m\u00fcssen entweder vom gleichen Typ und Material sein (wie zwei Eisenschwerter) oder ein Gegenstand und ein verzaubertes Buch mit einer anwendbaren Verzauberung (wie ein Bogen und ein verzaubertes Buch der Unendlichkeit).<\/p>\n\n\n\n<p>Die Kombination von zwei Gegenst\u00e4nden, B\u00fcchern oder einem Gegenstand mit derselben Verzauberung auf derselben Stufe ergibt einen Gegenstand oder ein Buch mit der n\u00e4chsth\u00f6heren Stufe dieser Verzauberung bis zum maximal zul\u00e4ssigen Wert im \u00dcberlebensmodus; zum Beispiel ergibt ein Buch mit Stacheln I und St\u00e4rke II in Kombination mit einem Buch mit St\u00e4rke II ein Buch mit Stacheln I und St\u00e4rke III.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-minecraft-anvil.jpg\" alt=\"combine enchanting minecraft anvil\" class=\"wp-image-4345\" width=\"300\" height=\"213\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-minecraft-anvil.jpg 600w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-minecraft-anvil-300x213.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Zwei in einen Amboss verzauberte Diamantstifte.<\/figcaption><\/figure><\/div>\n\n\n<p>Um Gegenst\u00e4nde zu kombinieren, legt der Spieler den Zielgegenstand in den ersten Schlitz des Ambosses und den Opfergegenstand in den zweiten Schlitz. Wenn die Kombination erlaubt ist, erscheint der verzauberte Gegenstand im Ausgabeschlitz des Ambosses und die Kosten f\u00fcr die Erfahrungsstufe, die so genannten &#8220;Verzauberungskosten&#8221;, werden darunter angezeigt (gr\u00fcn, wenn der Spieler \u00fcber gen\u00fcgend Erfahrungsstufen verf\u00fcgt, rot, wenn er sie nicht hat). Um die Verzauberung abzuschlie\u00dfen, entfernt der Spieler den verzauberten Gegenstand aus dem Ausgabeschlitz des Ambosses, und seine Erfahrungsstufe wird entsprechend verringert.<\/p>\n\n\n\n<p>Die Kosten f\u00fcr die Erfahrung h\u00e4ngen von den Verzauberungen ab, wobei stark verzauberte Gegenst\u00e4nde mehr kosten. Wenn das Zielobjekt auch repariert wird, kostet dies ebenfalls mehr. Der Zielgegenstand kann auch umbenannt werden, was zus\u00e4tzliche Kosten verursacht. Au\u00dferdem gibt es einen kumulativen Aufpreis f\u00fcr fr\u00fchere Arbeiten am Amboss. Im \u00dcberlebensmodus sind Arbeiten, die mehr als 39 Erfahrungsstufen kosten, nicht erlaubt, obwohl es immer noch m\u00f6glich ist, dieselbe Arbeit in Etappen zu erledigen. Zum Beispiel kann ein besch\u00e4digter verzauberter Bogen auf einem Amboss mit einem gew\u00f6hnlichen Bogen repariert werden, und dann kann ein anderer verzauberter Bogen verwendet werden, um Verzauberungen mit dem reparierten Bogen zu kombinieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ein-verzaubertes-Buch-benutzen\"><\/span>Ein verzaubertes Buch benutzen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Verzauberte B\u00fccher k\u00f6nnen mit einem Zaubertisch hergestellt werden, um ein Buch zu verzaubern. (Sie k\u00f6nnen auch in erzeugten Truhen gefunden, mit Smaragden in einem Buchladen im Dorf gekauft oder aus einer Angelrute gefischt werden).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-book-minecraft.jpg\" alt=\"enchanting book in enchanting table\" class=\"wp-image-4349\" width=\"225\" height=\"160\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-book-minecraft.jpg 450w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/enchanting-book-minecraft-300x213.jpg 300w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption class=\"wp-element-caption\">Verzauberung eines Buches in einem Zaubertisch.<\/figcaption><\/figure><\/div>\n\n\n<p>Das Buch kann mehrere Verzauberungen jeder Art erhalten, aber nur die Verzauberungen, die f\u00fcr eine bestimmte Art von Objekt geeignet sind, k\u00f6nnen auf dieses Objekt angewendet werden. Zum Beispiel kann ein und dasselbe Buch sowohl die Verzauberungen &#8220;Apnoe&#8221; als auch &#8220;St\u00e4rke&#8221; erhalten, aber die Verzauberung &#8220;Apnoe&#8221; geht verloren, wenn das Buch auf einen anderen Gegenstand als einen Helm angewendet wird, und die Verzauberung &#8220;St\u00e4rke&#8221; geht verloren, wenn das Buch auf einen anderen Gegenstand als einen Bogen angewendet wird.<\/p>\n\n\n\n<p>Verzauberte B\u00fccher werden auf einem Amboss benutzt, um Gegenst\u00e4nde, einschlie\u00dflich anderer B\u00fccher, zu verzaubern. Sie k\u00f6nnen bestimmte Verzauberungen auf Gegenst\u00e4nde anwenden, die nicht \u00fcber einen Zaubertisch verzaubert werden k\u00f6nnen, z. B. Dornen auf Stiefel.<\/p>\n\n\n\n<p>Im Kreativmodus k\u00f6nnen B\u00fccher jeden Gegenstand mit einer beliebigen Verzauberung versehen, z. B. einen Stab mit der Verzauberung &#8220;R\u00fccksto\u00df II&#8221;.<\/p>\n\n\n\n<p>Die Erfahrungskosten f\u00fcr die Verwendung von B\u00fcchern sind deutlich geringer als die f\u00fcr die Kombination von Gegenst\u00e4nden mit \u00e4hnlichen Verzauberungen, da die Herstellung der B\u00fccher selbst Stufen kostet. Allerdings sind dies immer noch zus\u00e4tzliche Kosten, und Verzauberungsgegenst\u00e4nde haben direkt eine Chance, mehrere Verzauberungen zu erhalten. Der Vorteil von B\u00fcchern ist, dass sie f\u00fcr die Verwendung auf einem Gegenstand der Wahl gelagert werden k\u00f6nnen und kontrollierte Kombinationen erm\u00f6glichen.<\/p>\n\n\n\n<p>Ein Buch mit Behutsamkeit kann zum Beispiel auf einer Axt, einer Spitzhacke oder einer Schaufel verwendet werden, und der Spieler kann entscheiden, welcher Gegenstand welche Verzauberung erh\u00e4lt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Entzaubern-eines-Objekts\"><\/span>Entzaubern eines Objekts<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die einzige M\u00f6glichkeit, Gegenst\u00e4nde zu entzaubern, besteht darin, die Schleifscheibe zu benutzen oder sie zu reparieren. Die Verwendung der Schleifscheibe entfernt alle Verzauberungen (au\u00dfer dem Fluch der Bindung und dem Fluch des Verschwindens) und gibt entsprechend der Stufe der Verzauberung(en) und ihrem Wert Erfahrung zur\u00fcck.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/desanchanting-minecraft.jpg\" alt=\"disenchanting minecraft object with grinding wheel\" class=\"wp-image-4353\" width=\"338\" height=\"239\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/desanchanting-minecraft.jpg 450w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/08\/desanchanting-minecraft-300x213.jpg 300w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><figcaption class=\"wp-element-caption\">Schnittstelle der Schleifscheibe zur Entzauberung einer Spitzhacke.<\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Liste-der-Verzauberungen\"><\/span>Liste der Verzauberungen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Jede Verzauberung in der unten stehenden Tabelle enth\u00e4lt Attribute, die der Spieler im \u00dcberlebensmodus rechtm\u00e4\u00dfig erwerben kann. Andere Kombinationen sind im Kreativmodus oder mit Cheats, Mods oder Software von Drittanbietern m\u00f6glich.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Atmung<\/td><td>Verl\u00e4ngert die Atemzeit unter Wasser. Stapel mit einem Schildkr\u00f6tenpanzer<\/td><\/tr><tr><td>Bann<\/td><td>Erh\u00f6ht den Schaden an untoten Mobs<\/td><\/tr><tr><td>Behutsamkeit<\/td><td>Abgebaute Bl\u00f6cke fallen bis auf wenige Ausnahmen von selbst.<\/td><\/tr><tr><td>Dornen<\/td><td>Reflektiert einen Teil des erlittenen Schadens, wenn er getroffen wird, auf Kosten der Verringerung der Haltbarkeit mit jedem Proc.<\/td><\/tr><tr><td>Durchschuss<\/td><td>Pfeile gehen durch mehrere Objekte. Nur f\u00fcr die Armbrust verf\u00fcgbar.<\/td><\/tr><tr><td>Effizienz<\/td><td>Erh\u00f6ht die Abbau-Geschwindigkeit. Bei Anwendung auf eine Axt erh\u00f6ht sich die Chance, dass die Axt einen Schild bet\u00e4ubt, wobei die Grundchance 25% betr\u00e4gt und mit jeder Stufe der Effizienz um 5% steigt.<\/td><\/tr><tr><td>Eisl\u00e4ufer<\/td><td>Verwandelt das Wasser unter dem Spieler in gefrorenes Eis und verhindert den Schaden, den der Spieler erleiden w\u00fcrde, wenn er auf Magmabl\u00f6cken steht.<\/td><\/tr><tr><td>Entladung<\/td><td>Der Dreizack &#8220;entl\u00e4dt&#8221; einen Blitz auf ein getroffenes Objekt. Funktioniert nur bei Gewitter und wenn das Ziel nicht durch undurchsichtige Bl\u00f6cke behindert wird.<\/td><\/tr><tr><td>Explosionsschutz<\/td><td>Verringert Explosionsschaden und R\u00fccksto\u00df.<\/td><\/tr><tr><td>Federfall<\/td><td>Verringert Sturzsch\u00e4den.<\/td><\/tr><tr><td>Feuerschutz<\/td><td>Verringert Feuerschaden und Brenndauer.<br>Schlie\u00dft sich gegenseitig mit anderen Schutzma\u00dfnahmen aus.<\/td><\/tr><tr><td>Flamme<\/td><td>Pfeile setzen das Ziel in Brand und entz\u00fcnden bei einem Treffer TNT.<\/td><\/tr><tr><td>Fluch der Bindung<\/td><td>Gegenst\u00e4nde k\u00f6nnen nicht aus R\u00fcstungsslots entfernt werden, au\u00dfer im Kreativmodus oder aufgrund von Tod oder Bruch.<\/td><\/tr><tr><td>Fluch des Verschwindens<\/td><td>Der Gegenstand wird beim Tod zerst\u00f6rt.<\/td><\/tr><tr><td>Gl\u00fcck<\/td><td>Erh\u00f6ht bestimmte Blockabw\u00fcrfe. H\u00f6here Stufen erh\u00f6hen die Chancen.<\/td><\/tr><tr><td>Gl\u00fcck des Meeres<\/td><td>Erh\u00f6ht die Rate an guter Pl\u00fcnderung (Verzauberung B\u00fccher, etc.). H\u00f6here Levels Erh\u00f6hen die Chance. <\/td><\/tr><tr><td>Hacken<\/td><td>Erh\u00f6ht Schaden und Schildbet\u00e4ubung. <\/td><\/tr><tr><td>Haltbarkeit<\/td><td>Verringert die Wahrscheinlichkeit, dass ein Gegenstand Schaden nimmt. H\u00f6here Stufen verringern die Chance weiter. <\/td><\/tr><tr><td>Harpune<\/td><td>Der Dreizack verursacht zus\u00e4tzlichen Schaden an Mobs, die nat\u00fcrlich im Meer spawnen. In der Bedrock Edition verursacht das Aufspie\u00dfen auf einen Dreizack auch zus\u00e4tzlichen Schaden an Spielern oder Mobs im Wasser oder Regen. <\/td><\/tr><tr><td>Huschen<\/td><td>Erm\u00f6glicht es Ihnen, schneller zu gehen, w\u00e4hrend Sie in die Hocke gehen.<\/td><\/tr><tr><td>K\u00f6der<\/td><td>Verringert die Wartezeit, bis Fisch\/Schrott\/Pl\u00fcnderung &#8220;anbei\u00dft&#8221;. H\u00f6here Levels erh\u00f6hen die Geschwindigkeit. <\/td><\/tr><tr><td>Mehrfachschuss<\/td><td>Schie\u00dfen Sie 3 Pfeile auf Kosten eines Pfeils; nur ein Pfeil kann wiederhergestellt werden. <\/td><\/tr><tr><td>Nemesis der Gliederf\u00fc\u00dfer<\/td><td>Erh\u00f6ht den Schaden und wendet Verlangsamung IV auf Arthropoden-Mobs (Spinnen, H\u00f6hlenspinnen, Silberfischchen, Endermiten und Bienen) an. <\/td><\/tr><tr><td>Pl\u00fcnderung<\/td><td>Erh\u00f6ht die Pl\u00fcnderung von Mobs. H\u00f6here Stufen erh\u00f6hen die Pl\u00fcnderung. <\/td><\/tr><tr><td>Reparatur<\/td><td>Repariere den Gegenstand, w\u00e4hrend du XP-Kugeln erh\u00e4ltst. <\/td><\/tr><tr><td>R\u00fccksto\u00df<\/td><td>Increases knockback. <\/td><\/tr><tr><td>Schlag<\/td><td>Erh\u00f6ht den R\u00fccksto\u00df von Pfeilen. <\/td><\/tr><tr><td>Schnellladen<\/td><td>Verringert die Ladezeit der Armbrust. <\/td><\/tr><tr><td>Schusssicher<\/td><td>Verringert den Projektilschaden, z. B. durch Pfeile, geworfene Dreizacke, Ghast- und Flammenfeuerb\u00e4lle usw. <\/td><\/tr><tr><td>Schutz<\/td><td>Verringert die meisten Schadensarten um 4%[nur JE] oder 5%[nur BE] f\u00fcr jede Stufe. <\/td><\/tr><tr><td>Schwungkraft<\/td><td>Erh\u00f6ht den Schaden von Wischangriffen. <\/td><\/tr><tr><td>Sch\u00e4rfe<\/td><td>Erh\u00f6ht den Schaden von Nahkampfwaffen. <\/td><\/tr><tr><td>Seelenl\u00e4ufer<\/td><td>Erh\u00f6ht die Laufgeschwindigkeit auf Seelensand oder Seelenerde, besch\u00e4digt aber mit der Zeit die Stiefel <\/td><\/tr><tr><td>Sog<\/td><td>Der Dreizack wirft den Spieler mit sich, wenn er geworfen wird. Funktioniert nur in Wasser oder Regen. <\/td><\/tr><tr><td>St\u00e4rke<\/td><td>Erh\u00f6ht den Pfeilschaden. <\/td><\/tr><tr><td>Treue<\/td><td>Der Dreizack kehrt zur\u00fcck, nachdem er geworfen wurde. H\u00f6here Stufen verk\u00fcrzen die R\u00fcckkehrzeit. <\/td><\/tr><tr><td>Unendlichkeit<\/td><td>Beim Schie\u00dfen werden keine normalen Pfeile verbraucht. Enth\u00e4lt keine Pfeilspitzen oder Spektralpfeile. <\/td><\/tr><tr><td>Verbrennung<\/td><td>Setzt das Ziel in Brand. <\/td><\/tr><tr><td>Wasseraffinit\u00e4t<\/td><td>Behebt die Verlangsamung des Unterwasserbergbaus. <\/td><\/tr><tr><td>Wasserl\u00e4ufer<\/td><td>Erh\u00f6ht die Bewegungsgeschwindigkeit unter Wasser. <\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\"> Liste aller Verzauberungen in Minecraft <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"All 30+ Minecraft Enchantments Explained in 7 Minutes\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/IoMQCZVnV80?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Alle Minecraft Verzauberungen erkl\u00e4rt<\/figcaption><\/figure>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;4364&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;3&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this page&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (3 votes)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Minecraft Verzauberungen Anleitung&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (3 votes)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Verzauberung in Minecraft zeichnet sich dadurch aus, dass Werkzeuge, Waffen, B\u00fccher, R\u00fcstungen und einige andere Gegenst\u00e4nde \u00fcber den Verzauberungstisch<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"class_list":["post-4364","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/pages\/4364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/comments?post=4364"}],"version-history":[{"count":50,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/pages\/4364\/revisions"}],"predecessor-version":[{"id":21511,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/pages\/4364\/revisions\/21511"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/media?parent=4364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}