{"id":1257,"date":"2020-11-14T10:14:22","date_gmt":"2020-11-14T09:14:22","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=1257"},"modified":"2020-11-14T10:14:23","modified_gmt":"2020-11-14T09:14:23","slug":"wie-macht-man-einen-screenshot-in-minecraft","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/","title":{"rendered":"Wie macht man einen Screenshot in Minecraft ?"},"content":{"rendered":"\n<p>Welchen Sinn hat es, etwas in Minecraft zu bauen, wenn man es der Welt nicht zeigen kann? Deshalb haben wir diesen praktischen Leitfaden zusammengestellt, um Ihnen zu helfen, die besten Bildschirme in jeder Version zu erhalten.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a989737de1c7\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a989737de1c7\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Machen-Sie-einen-Screenshot-auf-PC-JAVA\" >Machen Sie einen Screenshot auf PC \/ JAVA<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Druecken-Sie-die-Taste-F2-auf-Ihrer-Tastatur-Fn-F2-unter-Mac\" >Dr\u00fccken Sie die Taste F2 auf Ihrer Tastatur (Fn + F2 unter Mac)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Im-Spiel-wird-eine-Nachricht-angezeigt-die-Ihnen-mitteilt-dass-der-Screenshot-gemacht-wurde\" >Im Spiel wird eine Nachricht angezeigt, die Ihnen mitteilt, dass der Screenshot gemacht wurde.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Um-Ihren-Screenshot-zu-finden-gehen-Sie-zum-Ordner-screenshots\" >Um Ihren Screenshot zu finden, gehen Sie zum Ordner \/screenshots.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Um-Ihren-Screenshot-zu-finden-gehen-Sie-zum-Ordner-Druecken-Sie-gleichzeitig-WINDOWS-R-und-geben-Sie-dann-appdata-in-das-Fenster\" >Um Ihren Screenshot zu finden, gehen Sie zum Ordner Dr\u00fccken Sie gleichzeitig WINDOWS + R und geben Sie dann %appdata% in das Fenster<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Navigieren-Sie-zum-Ordner-screenshots-im-Stammverzeichnis-von-Minecraft\" >Navigieren Sie zum Ordner \/screenshots im Stammverzeichnis von Minecraft<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Machen-Sie-einen-Screenshot-auf-PC-Windows-10\" >Machen Sie einen Screenshot auf PC \/ Windows 10<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Erstellen-eines-Screenshots-auf-der-Xbox-One\" >Erstellen eines Screenshots auf der Xbox One<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Machen-Sie-einen-Screenshot-auf-PS4\" >Machen Sie einen Screenshot auf PS4<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Erstellen-eines-Screenshots-auf-dem-Nintendo-Switch\" >Erstellen eines Screenshots auf dem Nintendo Switch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Ein-Bildschirmfoto-auf-dem-iPhone-machen\" >Ein Bildschirmfoto auf dem iPhone machen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Machen-Sie-einen-Screenshot-auf-Android\" >Machen Sie einen Screenshot auf Android<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/minecraft-tutos.com\/de\/wie-macht-man-einen-screenshot-in-minecraft\/#Erstellen-eines-Screenshots-auf-Xbox-360-und-Playstation-3\" >Erstellen eines Screenshots auf Xbox 360 und Playstation 3<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Machen-Sie-einen-Screenshot-auf-PC-JAVA\"><\/span>Machen Sie einen Screenshot auf PC \/ JAVA<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es ist sehr einfach, in Minecraft einen Screenshot zu machen:<\/p>\n\n\n<div id=\"rank-math-howto\" class=\"rank-math-block\">\n<div class=\"rank-math-howto-description\">\n\n<p>Wie man einen Screenshot von Minecraft macht.<\/p>\n\n<\/div>\n<p class=\"rank-math-howto-duration\"><strong>Gesamtzeit:<\/strong> <span>2 Minuten<\/span><\/p>\n<ol class=\"rank-math-steps \">\n<li id=\"howto-step-1605341166041\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Druecken-Sie-die-Taste-F2-auf-Ihrer-Tastatur-Fn-F2-unter-Mac\"><\/span>Dr\u00fccken Sie die Taste F2 auf Ihrer Tastatur (Fn + F2 unter Mac)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><p>Sie k\u00f6nnen den Schl\u00fcssel in den Optionen von Minecraft \u00e4ndern.<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1605341267397\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Im-Spiel-wird-eine-Nachricht-angezeigt-die-Ihnen-mitteilt-dass-der-Screenshot-gemacht-wurde\"><\/span>Im Spiel wird eine Nachricht angezeigt, die Ihnen mitteilt, dass der Screenshot gemacht wurde.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><p>Sie enth\u00e4lt Informationen \u00fcber die Zeit und das Datum des Fangs.<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1605341268433\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Um-Ihren-Screenshot-zu-finden-gehen-Sie-zum-Ordner-screenshots\"><\/span>Um Ihren Screenshot zu finden, gehen Sie zum Ordner \/screenshots.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><p>Folgen Sie den nachstehenden Schritten, um ihn zu finden.<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1605341269203\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Um-Ihren-Screenshot-zu-finden-gehen-Sie-zum-Ordner-Druecken-Sie-gleichzeitig-WINDOWS-R-und-geben-Sie-dann-appdata-in-das-Fenster\"><\/span>Um Ihren Screenshot zu finden, gehen Sie zum Ordner Dr\u00fccken Sie gleichzeitig WINDOWS + R und geben Sie dann %appdata% in das Fenster<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><p>Best\u00e4tigen Sie mit der Eingabetaste.<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1605341270006\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Navigieren-Sie-zum-Ordner-screenshots-im-Stammverzeichnis-von-Minecraft\"><\/span>Navigieren Sie zum Ordner \/screenshots im Stammverzeichnis von Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><p>Hier werden die Screenshots aufgezeichnet.<\/p>\n<\/div>\n<\/li>\n<\/ol>\n<\/div>\n\n\n<p><strong><strong>Unter Mac finden Sie den Ordner<\/strong>: <\/strong>simultaneously press SHIFT + COMMAND + G from the Finder. Enter \/Users\/YOURUSER\/library\/Application Support\/Minecraft in the window.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Machen-Sie-einen-Screenshot-auf-PC-Windows-10\"><\/span>Machen Sie einen Screenshot auf PC \/ Windows 10<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u00d6ffnen Sie das Windows-Spiel mit der Windows-Schaltfl\u00e4che. Oder halten Sie die Windows-, Alt- und Prtscn-Taste zusammen, um sofort einen Screenshot zu machen.<\/p>\n\n\n\n<p>Wenn Sie die Tasten Shift, Cmd und 4 gleichzeitig dr\u00fccken, erhalten Sie einen vollst\u00e4ndigen Screenshot. Diese werden auf Ihrem Desktop gespeichert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Erstellen-eines-Screenshots-auf-der-Xbox-One\"><\/span>Erstellen eines Screenshots auf der Xbox One<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Dr\u00fccken Sie zweimal die Xbox-Taste auf Ihrem Controller. Sie k\u00f6nnen nun Y dr\u00fccken, um einen Screenshot zu machen, oder X, um einen Videoclip aufzunehmen. Gehen Sie dann auf Xbox.com, loggen Sie sich in Ihr Xbox Live-Konto ein, und Sie finden alle Ihre Screenshots im Abschnitt &#8220;Aufnahmen&#8221; auf Ihrer Profilseite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Machen-Sie-einen-Screenshot-auf-PS4\"><\/span>Machen Sie einen Screenshot auf PS4<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Sie k\u00f6nnen die SHARE-Taste auf Ihrem Controller gedr\u00fcckt halten, um einen Screenshot zu machen. Oder dr\u00fccken Sie die SHARE-Taste, um ein neues Men\u00fc mit Optionen zum Erstellen eines Screenshots, zur Videoaufnahme und zur Weitergabe Ihrer Aufnahmen zu \u00f6ffnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Erstellen-eines-Screenshots-auf-dem-Nintendo-Switch\"><\/span>Erstellen eines Screenshots auf dem Nintendo Switch<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Sehen Sie den netten kleinen Knopf auf der linken Seite? Der mit der Kamera drauf? Dr\u00fccken Sie ihn, um einen Screenshot zu machen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ein-Bildschirmfoto-auf-dem-iPhone-machen\"><\/span>Ein Bildschirmfoto auf dem iPhone machen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Dr\u00fccken Sie gleichzeitig die Schlaf-\/Wach-Taste Ihres Telefons und die Home-Taste, um den Screenshot aufzunehmen. Sie finden Ihre Screenshots in der Anwendung Fotos unter Alben und dann Film.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Machen-Sie-einen-Screenshot-auf-Android\"><\/span>Machen Sie einen Screenshot auf Android<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Telefone mit Android 4.0 und h\u00f6her sind einfach. Dr\u00fccken Sie einfach gleichzeitig die Lautst\u00e4rke- und die Einschalttaste. \u00c4ltere Android-Modelle sind kniffliger, da sie sich von Telefon zu Telefon unterscheiden. Suchen Sie online nach Ihrem Telefonmodell, um zu sehen, ob es \u00fcber eine Screenshot-Funktion verf\u00fcgt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Erstellen-eines-Screenshots-auf-Xbox-360-und-Playstation-3\"><\/span>Erstellen eines Screenshots auf Xbox 360 und Playstation 3<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Hier werden die Dinge kompliziert! Weder die Playstation 3 noch die Xbox 360 haben eingebaute Screen-Capture-Funktionen, die Minecraft unterst\u00fctzen. Aber wenn Sie in Video-Capture-Technologie investieren, k\u00f6nnen Sie Screenshots machen. Es ist nicht die billigste L\u00f6sung, aber schauen Sie sich um, und Sie werden bald in der Lage sein, die Bildschirme dieser \u00e4lteren Konsolenversionen zu benutzen.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;1257&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (1 vote)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Wie macht man einen Screenshot in Minecraft ?&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (1 vote)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Welchen Sinn hat es, etwas in Minecraft zu bauen, wenn man es der Welt nicht zeigen kann? Deshalb haben wir<\/p>\n","protected":false},"author":2,"featured_media":1248,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[31],"tags":[],"class_list":["post-1257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wie-man","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/1257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/comments?post=1257"}],"version-history":[{"count":4,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/1257\/revisions"}],"predecessor-version":[{"id":1261,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/1257\/revisions\/1261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/media\/1248"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/media?parent=1257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/categories?post=1257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/tags?post=1257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}