{"id":15199,"date":"2022-08-03T10:10:50","date_gmt":"2022-08-03T08:10:50","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=15199"},"modified":"2022-08-03T10:11:34","modified_gmt":"2022-08-03T08:11:34","slug":"mod-schematica","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/","title":{"rendered":"Schematica &#8211; Mod &#8211; 1.7.10 \u2192 1.12.2"},"content":{"rendered":"\n<p>Haben Sie schon einmal eine coole Struktur auf einer Karte gefunden und wollten sie auf Ihrer pers\u00f6nlichen Karte reproduzieren ? St\u00e4ndig zwischen zwei Karten hin- und herspringen zu m\u00fcssen, um alles zu reproduzieren, ist nervig ! Aber das geh\u00f6rt jetzt alles der Vergangenheit an !<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"130\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica.png\" alt=\"logo schematica\" class=\"wp-image-15154\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica.png 400w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-300x98.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>Der Schematica-Mod von <em>Lunatrius<\/em>, der mit den neuesten Versionen von Minecraft kompatibel ist, f\u00fcgt deinem Spiel ein schematic System hinzu, das du auf jeder deiner Karten wiederverwenden kannst.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a988f7139146\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a988f7139146\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#Wie-funktioniert-es\" >Wie funktioniert es ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#Einen-schematic-speichern\" >Einen schematic speichern<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#Einen-schematic-laden\" >Einen schematic laden<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#Den-schematic-bearbeiten\" >Den schematic bearbeiten<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#Herunterladen\" >Herunterladen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#%E2%9D%93-Was-ist-Schematica\" >\u2753 Was ist Schematica ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#%F0%9F%8E%AE-Wie-benutzt-man-Schematica\" >\ud83c\udfae Wie benutzt man Schematica ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#%E2%9D%93-Wo-kann-ich-schematic-finden\" >\u2753 Wo kann ich schematic finden ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/minecraft-tutos.com\/de\/mod-schematica\/#%F0%9F%92%BF-Mit-welchen-Versionen-von-Minecraft-ist-Schematica-kompatibel\" >\ud83d\udcbf Mit welchen Versionen von Minecraft ist Schematica kompatibel ?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wie-funktioniert-es\"><\/span>Wie funktioniert es ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Der Schematica-Mod integriert ein System zur Verwaltung von Schemata in Ihr Spiel, das unabh\u00e4ngig von den Karten funktioniert, auf denen Sie sich befinden. Einfach ausgedr\u00fcckt : Egal, auf welcher Karte Sie sich befinden, Sie k\u00f6nnen Ihr Men\u00fc \u00f6ffnen und auf Ihre gespeicherten Schemata zugreifen.<\/p>\n\n\n\n<p>Wenn Sie diese Schemata auf Ihrer Karte \u00f6ffnen, wird ein Geisterbild der gespeicherten Struktur erstellt, so dass Sie sie einfach kopieren k\u00f6nnen.<\/p>\n\n\n\n<p>Wenn Sie die Spielsteuerung aufrufen, sehen Sie mehrere neue Optionen, die mit der Mod zusammenh\u00e4ngen. Wir sind an den ersten drei interessiert.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"993\" height=\"232\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/01.png\" alt=\"Optionen schematica\" class=\"wp-image-15160\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/01.png 993w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/01-300x70.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/01-768x179.png 768w\" sizes=\"auto, (max-width: 993px) 100vw, 993px\" \/><figcaption><em>Die 3 wichtigsten Optionen dieses Mods.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Einen-schematic-speichern\"><\/span>Einen schematic speichern<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Mit dieser Option k\u00f6nnen Sie einen schematic erstellen und ihn in Ihrem Manager speichern.<\/p>\n\n\n\n<p>Wenn Sie diese Option aktivieren, wird ein Men\u00fc ge\u00f6ffnet.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-menu-1024x558.png\" alt=\"schematica-Men\u00fc\" class=\"wp-image-15166\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-menu-1024x558.png 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-menu-300x163.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-menu-768x418.png 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-menu-1536x837.png 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-menu.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em><em>Schematic<\/em><\/em> <em>Registrierungsmen\u00fc.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Die Optionen &#8220;Roter Punkt&#8221; und &#8220;Blauer Punkt&#8221; sind die Markierungen Ihres schematic : Sie grenzen Ihren schematic ab. Die X\/Y\/Z-Koordinaten unten erm\u00f6glichen es Ihnen, Ihre beiden Punkte genau zu positionieren, so dass die gesamte Struktur umgeben ist.<\/p>\n\n\n\n<p>Wenn Sie auf einen der Punkte dr\u00fccken, wird vor Ihnen ein transparenter Block erstellt: Dies ist die Darstellung Ihrer Auswahl. Sobald die beiden Punkte erstellt wurden, haben Sie einen visuellen \u00dcberblick \u00fcber Ihre Auswahl. Sie k\u00f6nnen die Koordinaten verwenden, um Ihre Auswahl zu verfeinern.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/structure-schematica-1024x558.jpg\" alt=\"Struktur schematica\" class=\"wp-image-15173\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/structure-schematica-1024x558.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/structure-schematica-300x163.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/structure-schematica-768x418.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/structure-schematica-1536x837.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/structure-schematica.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Die Struktur ist vollst\u00e4ndig ausgew\u00e4hlt.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Sobald Sie Ihre Struktur ausgew\u00e4hlt haben, \u00f6ffnen Sie einfach Ihr Men\u00fc erneut, geben Ihrer Struktur einen Namen und klicken auf &#8220;Speichern&#8221;.<\/p>\n\n\n\n<p>Dann ist Ihr schematic bereit f\u00fcr eine neue Verwendung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Einen-schematic-laden\"><\/span>Einen schematic laden<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"557\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/Screenshot-1-1024x557.jpg\" alt=\"einen Schaltplan mit schematica laden\" class=\"wp-image-15179\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/Screenshot-1-1024x557.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/Screenshot-1-300x163.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/Screenshot-1-768x418.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/Screenshot-1-1536x836.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/Screenshot-1.jpg 1919w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Men\u00fc zur Auswahl von Schaltpl\u00e4nen.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Mit dieser Option k\u00f6nnen Sie Ihre Liste von schematic anzeigen lassen. Auch hier k\u00f6nnen Sie sich auf einer beliebigen Karte befinden, die Liste bleibt dieselbe. Um den gew\u00fcnschten schematic auszuw\u00e4hlen, klicken Sie ihn einfach an und dann auf &#8220;Fertig&#8221;.<\/p>\n\n\n\n<p>Ihre Schemata erscheinen dann vor Ihnen in Form von Geisterbl\u00f6cken.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-ghost-blocks-1024x558.jpg\" alt=\"schematica Geisterbl\u00f6cke\" class=\"wp-image-15185\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-ghost-blocks-1024x558.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-ghost-blocks-300x163.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-ghost-blocks-768x418.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-ghost-blocks-1536x837.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/schematica-ghost-blocks.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Ooouh, dieses Redstone-System ist ein Spuk !<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p><em>Aber Vorsicht<\/em> : Die Bl\u00f6cke sind nicht echt ! Es handelt sich nur um eine &#8220;Zeichnung&#8221; deiner vorherigen Konstruktion. Wenn du sie echt haben willst, musst du sie \u00fcberbauen. Die Geisterbl\u00f6cke verschwinden, wenn du einen Block an ihre Stelle setzt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Den-schematic-bearbeiten\"><\/span>Den schematic bearbeiten<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Mit dieser letzten Option k\u00f6nnen Sie Ihre Konstruktion fertig stellen.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/handling-menu-1024x558.png\" alt=\"\" class=\"wp-image-15191\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/handling-menu-1024x558.png 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/handling-menu-300x163.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/handling-menu-768x418.png 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/handling-menu-1536x837.png 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/08\/handling-menu.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Und schlie\u00dflich das Manipulationsmen\u00fc.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Sie haben hier mehrere Optionen. Mit den Schaltfl\u00e4chen in der Mitte und unten links auf dem Bildschirm k\u00f6nnen Sie den schematic nach Belieben verschieben, so dass Sie ihn dort platzieren k\u00f6nnen, wo Sie Ihre k\u00fcnftige Konstruktion aufbauen m\u00f6chten.<\/p>\n\n\n\n<p>Mit der Schaltfl\u00e4che &#8220;Entladen&#8221; k\u00f6nnen Sie den schematic einfach wegschicken.<br>Mit der Option &#8220;Alle\/Schichten&#8221; k\u00f6nnen Sie sich den gesamten schematic oder Schicht f\u00fcr Schicht ansehen, falls der Blockstapel zu unhandlich wird, um ihn zu bauen.<br>Die Schaltfl\u00e4che &#8220;Materialien&#8221; listet die Anzahl der Bl\u00f6cke in der Konstruktion auf, so dass Sie sehen k\u00f6nnen, wie viele Sie ben\u00f6tigen, um die Struktur zu reproduzieren.<\/p>\n\n\n\n<p>So k\u00f6nnen Sie Ihre Bauwerke, Redstone-Systeme oder Dekorationen auf jeder Karte wiederverwenden !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Herunterladen\"><\/span>Herunterladen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\ud83d\udc4b Suchst du nach einer Alternative zu Schematica, die mit den neuesten Versionen von Minecraft funktioniert ? Probiere <a href=\"https:\/\/minecraft-tutos.com\/de\/mod-litematica\/\">Litematica <\/a>!<\/p>\n\n\n\n<p>Diese Mod ben\u00f6tigt Forge, um zu funktionieren. Wenn du diese Mod in Minecraft Version 1.7.2 oder h\u00f6her verwendest, ben\u00f6tigst du au\u00dferdem die LunatriusCore Mod.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/minecraft-tutos.com\/de\/minecraft-forge-herunterladen-und-installieren\/\">Herunterladen von Forge<\/a><\/li><li><a href=\"https:\/\/minecraft-tutos.com\/de\/wie-installiert-man-einen-minecraft-mod\/\">Erfahren Sie, wie man einen Minecraft-Mod installiert<\/a><\/li><li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/lunatriuscore\" target=\"_blank\" rel=\"noreferrer noopener\">LunatriusCore Download-Link<\/a><\/li><li>Schematica Download-Link :<ul><li><a href=\"https:\/\/minecraft.curseforge.com\/projects\/schematica\/files\/2274295\/download\" target=\"_blank\" rel=\"noopener\">Schematica [1.7.10]<\/a><\/li><\/ul><ul><li><a href=\"https:\/\/minecraft.curseforge.com\/projects\/schematica\/files\/2279147\/download\" target=\"_blank\" rel=\"noopener\">Schematica [1.8.9]<\/a><\/li><li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/schematica\/download\/2312511\" target=\"_blank\" rel=\"noreferrer noopener\">Schematica [1.9.4]<\/a><\/li><li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/schematica\/download\/2342254\" target=\"_blank\" rel=\"noreferrer noopener\">Schematica [1.10.2]<\/a><\/li><li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/schematica\/download\/2402019\" target=\"_blank\" rel=\"noreferrer noopener\">Schematica [1.11]<\/a><\/li><li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/schematica\/download\/2554100\" target=\"_blank\" rel=\"noreferrer noopener\">Schematica [1.12.2]<\/a><\/li><\/ul><\/li><\/ul>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/schematica\" target=\"_blank\" rel=\"noreferrer noopener\">Link zum Originalbeitrag<\/a><\/p>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1659384421345\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%E2%9D%93-Was-ist-Schematica\"><\/span>\u2753 Was ist Schematica ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Es ist eine Mod f\u00fcr Minecraft, die ein Schemasystem hinzuf\u00fcgt, das du auf deinen Karten wiederverwenden kannst.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1659384446255\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%F0%9F%8E%AE-Wie-benutzt-man-Schematica\"><\/span>\ud83c\udfae Wie benutzt man Schematica ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Nach der Installation der Mod musst du eine schematica speichern und sie dann dort laden, wo du sie integrieren m\u00f6chtest (in deiner aktuellen Welt oder einer anderen).<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1659384467422\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%E2%9D%93-Wo-kann-ich-schematic-finden\"><\/span>\u2753 Wo kann ich schematic finden ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Du kannst sie in der entsprechenden Kategorie von Planteminecraft finden.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1659384487332\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%F0%9F%92%BF-Mit-welchen-Versionen-von-Minecraft-ist-Schematica-kompatibel\"><\/span>\ud83d\udcbf Mit welchen Versionen von Minecraft ist Schematica kompatibel ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Ab heute ist Schematica kompatibel mit den Versionen: 1.7.10, 1.8.9, 1.9.4, 1.10.2, 1.11.2 und 1.12.2.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;15199&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (1 vote)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Schematica - Mod - 1.7.10 \u2192 1.12.2&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (1 vote)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Haben Sie schon einmal eine coole Struktur auf einer Karte gefunden und wollten sie auf Ihrer pers\u00f6nlichen Karte reproduzieren ?<\/p>\n","protected":false},"author":2,"featured_media":15246,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-15199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mod-de","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/15199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/comments?post=15199"}],"version-history":[{"count":6,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/15199\/revisions"}],"predecessor-version":[{"id":15255,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/15199\/revisions\/15255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/media\/15246"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/media?parent=15199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/categories?post=15199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/tags?post=15199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}