{"id":20707,"date":"2023-12-30T10:20:29","date_gmt":"2023-12-30T09:20:29","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=20707"},"modified":"2023-12-30T10:20:31","modified_gmt":"2023-12-30T09:20:31","slug":"enderdrache-minecraft-alles-ueber-diese-kreatur","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/","title":{"rendered":"Enderdrache Minecraft : Alles \u00fcber diese Kreatur"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/ender-dragon-animation-minecraft.webp\" alt=\"animation enderdrache minecraft\" class=\"wp-image-20580\" width=\"189\" height=\"193\" title=\"\"><\/figure><\/div>\n\n\n<p><strong>Der Enderdrache<\/strong> ist ein riesiger, fliegender, feindseliger Minecraft-Mob, den du findest, wenn du zum ersten Mal das End durch ein <a href=\"https:\/\/minecraft-tutos.com\/de\/wie-baue-ich-das-enderportal\/\">End-Portal<\/a> betrittst. Er ist die gr\u00f6\u00dfte Kreatur, die auf nat\u00fcrliche Weise im Spiel vorkommt.<\/p>\n\n\n\n<p>Er bewacht den Zugang zu den End-Gateways, die den Zugang zu den \u00e4u\u00dferen Inseln der End erm\u00f6glichen, sowie das Exit-Portal, das die R\u00fcckkehr in die normale Welt und den Zugang zum Abspann von Minecraft erm\u00f6glicht.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a9897c0488a4\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9897c0488a4\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Erscheinungsbild\" >Erscheinungsbild<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Erstes-Erscheinen\" >Erstes Erscheinen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Wiedererscheinen-Beschwoerung\" >Wiedererscheinen \/ Beschw\u00f6rung<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Pluenderung\" >Pl\u00fcnderung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Verhalten\" >Verhalten<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Bewegungen\" >Bewegungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Angriff\" >Angriff<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Wache\" >Wache<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Anvisieren\" >Anvisieren<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Bestrafung\" >Bestrafung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Tauchen\" >Tauchen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Abheben\" >Abheben<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Aufladen\" >Aufladen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Barsch\" >Barsch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Entfliehen\" >Entfliehen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Der-Atem-des-Drachen\" >Der Atem des Drachen<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/minecraft-tutos.com\/de\/enderdrache-minecraft-alles-ueber-diese-kreatur\/#Minecraft-Drache-Feuerball\" >Minecraft Drache Feuerball<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Erscheinungsbild\"><\/span>Erscheinungsbild<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Erstes-Erscheinen\"><\/span>Erstes Erscheinen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Der Enderdrache erscheint 1 Sekunde, nachdem ein Wesen das End-Portal betreten hat.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/minecraft-ender-dragon.webp\" alt=\"Minecraft Enderdrache\" class=\"wp-image-20586\" width=\"566\" height=\"344\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/minecraft-ender-dragon.webp 1000w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/minecraft-ender-dragon-300x182.webp 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/minecraft-ender-dragon-768x467.webp 768w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><figcaption class=\"wp-element-caption\"><em>Das Modell des Enderdrachens<\/em><\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wiedererscheinen-Beschwoerung\"><\/span>Wiedererscheinen \/ Beschw\u00f6rung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Du kannst den <strong>Drachen wieder beschw\u00f6ren, indem du vier Endkristalle an den R\u00e4ndern des Ausgangsportals platzierst<\/strong>, einen an jeder Ecke. Wenn du ihn wieder beschw\u00f6rst, zeigen die vier Endkristalle auf die Spitze jeder S\u00e4ule und l\u00f6sen eine Reihe von Explosionen aus, die die Obsidians\u00e4ulen, Eisenst\u00e4be und Kristalle zur\u00fccksetzen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/respawn-resurrect-ender-dragon-minecraft.webp\" alt=\"Endkristalle zur Wiederbelebung des Enderdrachens\" class=\"wp-image-20592\" width=\"584\" height=\"328\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/respawn-resurrect-ender-dragon-minecraft.webp 854w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/respawn-resurrect-ender-dragon-minecraft-300x169.webp 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/respawn-resurrect-ender-dragon-minecraft-768x432.webp 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><figcaption class=\"wp-element-caption\"><em>Dieses Bild zeigt, wie der Spieler die Enderkristalle anordnen kann, um den Enderdrachen wieder auftauchen zu lassen.<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Die Spitze jeder S\u00e4ule explodiert und zerst\u00f6rt alle vom Spieler platzierten Bl\u00f6cke. Schlie\u00dflich zeigen alle Kristalle auf die Koordinaten (0.0, 128, 0.0) und der Enderdrache erscheint dort. Wenn der Spieler das <a href=\"https:\/\/minecraft-tutos.com\/de\/wie-man-ein-drachenei-in-minecraft-ausbruetet-und-den-ender-drachen-wiederbelebt\/\">Drachenei nicht aufhebt<\/a> und erneut beginnt, den Drachen zu beschw\u00f6ren, verschwindet das Drachenei.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pluenderung\"><\/span>Pl\u00fcnderung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Wenn der Enderdrache zum ersten Mal get\u00f6tet wird, geschieht Folgendes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Er erhebt sich langsam, wobei seine Fl\u00fcgel und sein K\u00f6rper immer mehr besch\u00e4digt werden, bis er in Lichtstrahlen verschwindet, die aus seinem Zentrum herausschie\u00dfen.<\/li>\n\n\n\n<li>Es gibt eine Explosion von 12.000 Erfahrungspunkten, genug, um einen Spieler von Stufe 0 auf Stufe 68 zu bringen. Wenn der Spieler auf der Spitze der Felsstruktur get\u00f6tet wird, k\u00f6nnen einige Erfahrungspunkte in das Ausgangsportal fallen. Die Erfahrungspunkte k\u00f6nnen dann in der normalen Welt zur\u00fcckgewonnen werden.<\/li>\n\n\n\n<li>Die Bedrock-Struktur f\u00fcllt sich mit einer Schnittstelle, die der des Endportals \u00e4hnelt, und wird zum Ausgangsportal, das es dem Spieler erm\u00f6glicht, sich in die normale Welt zu <a href=\"https:\/\/minecraft-tutos.com\/de\/wie-man-in-minecraft-teleportieren\/\">teleportieren<\/a> und an dem Punkt, an dem er erscheint, wieder zu erscheinen.<\/li>\n\n\n\n<li>Ein Drachenei erscheint \u00fcber der zentralen Felsenstruktur der Insel. Befindet sich ein Block genau \u00fcber der Mitte der zentralen Felsstruktur, erscheint das Drachenei 1 Block \u00fcber dem h\u00f6chsten Block. Liegt der h\u00f6chste Block an der H\u00f6hengrenze, erscheint das Drachenei nicht.<\/li>\n\n\n\n<li>Es wird ein Endportal erzeugt, das in einem Radius von 75 bis 100 Bl\u00f6cken um das Ausgangsportal schwebt.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"328\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/explosion-dead-ender-dragon-minecraft.webp\" alt=\"Minecraft Enderdrache Todesexplosion\" class=\"wp-image-20598\" title=\"\"><figcaption class=\"wp-element-caption\"><em>Enderdrache Todesexplosion.<\/em><\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Verhalten\"><\/span>Verhalten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>W\u00e4hrend des Kampfes gegen den Enderdrachen wird eine einzigartige Musik namens &#8220;Boss&#8221; abgespielt, die R\u00e4nder des Bildschirms verdunkeln sich, ein schwarzer Nebel erscheint und <a href=\"https:\/\/minecraft-tutos.com\/de\/chunks-in-minecraft-was-sind-sie-wie-kann-man-sie-anzeigen-und-welche-groesse-haben-sie\/\">chunks<\/a> um das Endportal werden st\u00e4ndig angezeigt, unabh\u00e4ngig von der Rendering-Distanz. Diese Ph\u00e4nomene treten auf, solange sich mindestens ein Spieler innerhalb von 192 Bl\u00f6cken befindet.<\/p>\n\n\n\n<figure class=\"wp-block-audio aligncenter\"><audio controls src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/boss-music-ender-dragon-minecraft.ogg\"><\/audio><figcaption class=\"wp-element-caption\"><em>Die &#8220;Boss&#8221;-Musik, die in Minecraft gespielt wird, wenn der Spieler gegen den Enderdrachen k\u00e4mpft.<\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>Der Enderdrache hat einen hellvioletten Gesundheitsbalken mit 200 Trefferpunkten oder 100\u2665<\/strong>, der oben auf dem Bildschirm des Spielers erscheint. Seine Gesundheit wird durch nahe gelegene Endkristalle wiederhergestellt, was durch einen magischen wei\u00dfen Strahl angezeigt wird, der den Drachen und den Kristall verbindet. Die Zerst\u00f6rung eines Endkristalls, der den Drachen aktiv heilt, f\u00fcgt ihm 10 Schadenspunkte oder 5\u2665 zu.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"876\" height=\"119\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/lifebar-ender-dragon.jpeg\" alt=\"enderdrache minecraft lebensleiste\" class=\"wp-image-20610\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/lifebar-ender-dragon.jpeg 876w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/lifebar-ender-dragon-300x41.jpeg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/lifebar-ender-dragon-768x104.jpeg 768w\" sizes=\"auto, (max-width: 876px) 100vw, 876px\" \/><figcaption class=\"wp-element-caption\"><em>Der Lebensbalken des Enderdrachens.<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Der Drache kann nur durch Explosionen und vom Spieler verursachten Schaden Schaden erleiden und erleidet Schaden, wenn er an einem anderen Teil als seinem Kopf getroffen wird, was ihn zu der widerstandsf\u00e4higsten Kreatur im Spiel macht. Es ist unm\u00f6glich, ihn zu ersticken. Dar\u00fcber hinaus ist der Drache immun gegen alle Statuseffekte.<\/p>\n\n\n\n<p>Mit der Tastenkombination <code>F3<\/code> + <code>B<\/code> erscheint die Kollisionsbox des Drachens. Er kann nirgendwo in diesem gro\u00dfen Volumen besch\u00e4digt werden : Acht gr\u00fcne Kollisionsunterboxen werden ebenfalls angezeigt, die angeben, wo der Drache Schaden nehmen kann : Schwanz, K\u00f6rper, Kopf und Fl\u00fcgel.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/hitbox-ender-dragon-minecraft.webp\" alt=\"Gr\u00fcne Hitboxen des Minecraft-Drachens Enderdrache\" class=\"wp-image-20616\" width=\"532\" height=\"299\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/hitbox-ender-dragon-minecraft.webp 854w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/hitbox-ender-dragon-minecraft-300x169.webp 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/hitbox-ender-dragon-minecraft-768x432.webp 768w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><figcaption class=\"wp-element-caption\"><em>Die gr\u00fcnen Hitboxen des Enderdrachens.<\/em><\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Bewegungen\"><\/span>Bewegungen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Der Enderdrache ist eine fliegende Kreatur, die nicht auf dem Boden bleiben kann. Er fliegt um die Hauptinsel herum, w\u00e4hrend er gegen den Spieler k\u00e4mpft.<\/p>\n\n\n\n<p>Der Drache kann durch alle Bl\u00f6cke hindurchfliegen und fast alle Bl\u00f6cke zerst\u00f6ren, kann aber dennoch von flie\u00dfendem Wasser, Lava und der Blasens\u00e4ule getroffen werden. Unzerst\u00f6rbare Bl\u00f6cke sind solche, die auf der zentralen Insel des Endes auf nat\u00fcrliche Weise entstehen, und solche, die so konstruiert sind, dass sie unzerst\u00f6rbar sind, wie z. B. der Endstein und die Wiederauftauch-Anker.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Angriff\"><\/span>Angriff<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Der Drache greift nie andere Wesen als den Spieler an, obwohl andere Kreaturen dem Drachen gegen\u00fcber feindlich gesinnt sein k\u00f6nnen, wenn er getroffen wird. Dennoch kann der Drache manchmal Vergeltung an anderen Kreaturen \u00fcben, wenn er Projektilschaden erleidet. Jedes Wesen, das von seinen Fl\u00fcgeln getroffen wird, erleidet 5 Schaden (oder 10, wenn es von seinem Kopf getroffen wird). In der Java-Edition kann man in die Luft geschleudert werden, was zum Tod f\u00fchren kann, wenn man zu weit f\u00e4llt, oder sogar von der Insel.<\/p>\n\n\n\n<p>Der Enderdrache hat mehrere Hauptverhaltenszust\u00e4nde :<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wache\"><\/span>Wache<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:29% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/guard-attack-ender-dragon-minecraft-150x150-2.png\" alt=\"Wache Angriff Enderdrache Minecraft\" class=\"wp-image-20628 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Der Drache beginnt in diesem Zustand und umkreist den Ring aus Obsidians\u00e4ulen, entweder au\u00dferhalb, wenn noch Endkristalle vorhanden sind, oder innerhalb, wenn die Kristalle zerst\u00f6rt sind. Jedes Mal, wenn ein Kristall zerst\u00f6rt wird, erleidet er Schaden und es ist wahrscheinlicher, dass der Drache seinen Zustand \u00e4ndert.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Anvisieren\"><\/span>Anvisieren<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:28% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/targeting-2-attack-ender-dragon-minecraft-150x150-1.png\" alt=\"zielgerichteter angriff enderdrache minecraft\" class=\"wp-image-20634 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Wenn der Drache weniger als 10 Bl\u00f6cke oder mehr als 150 Bl\u00f6cke von seinem aktuellen Ziel entfernt ist, versucht er, ein neues Ziel zu w\u00e4hlen. Erleidet er dabei Schaden, zielt er auf einen Punkt direkt hinter ihm, was ihn zwingt, sich abzuwenden und ein neues Ziel zu w\u00e4hlen.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Bestrafung\"><\/span>Bestrafung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:28% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/strafing-attack-ender-dragon-minecraft-150x150-1.png\" alt=\"Maschinengewehr-Angriff Enderdrache Minecraft\" class=\"wp-image-20640 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Nachdem er einen Endkristall zerst\u00f6rt hat, wechselt der Drache in den Streifschussmodus. Sobald er sich in einem Radius von 64 Bl\u00f6cken befindet, feuert er einen Feuerball auf den Spieler ab. Danach beginnt der Drache wieder zu kreisen.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tauchen\"><\/span>Tauchen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:28% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/dive-attack-ender-dragon-minecraft-150x150-1.png\" alt=\"Tauchangriff Enderdrache Minecraft\" class=\"wp-image-20646 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Der Drache taucht auf die Position des Zielspielers, die beim Start des Tauchgangs eingenommen wird. Nach diesem Zustand beginnt der Drache wieder zu kreisen, unabh\u00e4ngig davon, ob er den Spieler ber\u00fchrt hat oder nicht.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Abheben\"><\/span>Abheben<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:27% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/takeoff-attack-ender-dragon-minecraft-150x150-1.png\" alt=\"Abheben Angriff Enderdrache Minecraft\" class=\"wp-image-20652 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Nach vier aufeinanderfolgenden Atemangriffen oder wenn der Drache innerhalb von 150 Bl\u00f6cken keinen Spieler findet, hebt er von seiner Sitzstange ab. Er hebt immer auf dem Schwierigkeitsgrad Friedlich ab, wodurch Nahkampfhiebe schwierig zu landen sind. Nach diesem Zustand beginnt der Drache wieder zu kreisen.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Aufladen\"><\/span>Aufladen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:27% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/charge-attack-ender-dragon-minecraft-150x150-1.png\" alt=\"angriff enderdrache minecraft\" class=\"wp-image-20658 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Wenn sich der Spieler nicht innerhalb von 5 Sekunden nach der Landung des Drachens in der N\u00e4he des Portals befindet, l\u00e4dt er Spieler in einem Umkreis von 150 Bl\u00f6cken auf.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Barsch\"><\/span>Barsch<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:26% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/perch-attack-ender-dragon-minecraft-150x150-1.png\" alt=\"Barsch-Angriff Enderdrache Minecraft\" class=\"wp-image-20664 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Wenn der Drache auf der Hut ist und das Ende des Pfades erreicht hat, hat er eine Chance von 1 zu (3 + lebende Kristalle), die Struktur des Ausgangsportals zu erreichen (wenn m\u00f6glich von der dem Spieler gegen\u00fcberliegenden Seite) und landet auf dem h\u00f6chsten Block der Koordinaten. Befindet sich kein Block in (x=0, z=0), bleibt der Drache stehen, wenn er die Sitzstange passiert.<\/p>\n\n\n\n<p>In diesem Zustand ist der Drache immun gegen Pfeile; sie fangen alle Feuer und prallen ab. In der Java-Version ist er auch immun gegen Dreizacke, die in diesem Zustand geworfen werden.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Entfliehen\"><\/span>Entfliehen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/escape-dragon-attack-ender-dragon-minecraft-150x150-1.png\" alt=\"Flucht Angriff Enderdrache Minecraft\" class=\"wp-image-20670 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Wenn der kumulierte Schaden, den er w\u00e4hrend des Sitzens erlitten hat, 50 (25\u2665) \u00fcbersteigt, fliegt der Drache weg und setzt den Schadensakkumulator zur\u00fcck0 Der Akkumulator wird nicht zur\u00fcckgesetzt, wenn er nicht genug Schaden erlitten hat. Der Drache beginnt nach diesem Zustand wieder zu kreisen.<\/p>\n\n\n\n<p>In der Java-Edition fliegt der Drache, wenn er einen t\u00f6dlichen Schlag erleidet, zum Ausgangsportal, bevor er stirbt, es sei denn, er kann innerhalb von 150 Bl\u00f6cken nicht gefunden werden oder er befindet sich innerhalb von Bl\u00f6cken.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Der-Atem-des-Drachen\"><\/span>Der Atem des Drachen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/escape-dragon-attack-ender-dragon-minecraft-150x150-2.png\" alt=\"Atem des Drachens Angriff Enderdrache Minecraft\" class=\"wp-image-20676 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Wenn sich der Spieler nicht auf dem Schwierigkeitsgrad Friedlich befindet, br\u00fcllt der Drache nach 1,25 Sekunden, wenn er sich in einem Umkreis von 20 Bl\u00f6cken um das Ausgangsportal befindet, und setzt seinen 3-sek\u00fcndigen Atemangriff ein, der dem Spieler \u00e4hnlichen Schaden zuf\u00fcgt wie ein anhaltender Trank mit Sofortschaden.<\/p>\n<\/div><\/div>\n\n\n\n<p>Ein Bereich mit sichtbaren Partikeln in Form einer horizontalen Scheibe, die einen Block hoch ist und einen Durchmesser von 5-6 Bl\u00f6cken hat, erscheint an der Stelle, an der der Angriff getroffen wurde, entweder auf dem Boden oder in der Luft schwebend, wo immer der Angriff einen Block getroffen hat. Der Bereich der sch\u00e4digenden Wirkung, in dem der Spieler Schaden erleidet, ist auf einen kleineren Bereich in der Mitte dieser sichtbaren Wolke begrenzt, der etwa 3 bis 4 Bl\u00f6cke umfasst.<\/p>\n\n\n\n<p>Der sch\u00e4dliche Teil der violetten Wolken, die der Atem des Drachens ausst\u00f6\u00dft, kann in einer Glasphiole gesammelt werden, um den Atem des Drachens zu erhalten. Durch schnelles Einsammeln aller sch\u00e4dlichen Bl\u00f6cke, in der Regel etwa drei, kann sogar ein direkter Treffer des Atemangriffs weitgehend, wenn nicht sogar vollst\u00e4ndig, negiert werden, bevor der Spieler Schaden erleidet.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"546\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/ender-dragon-minecraft-1024x546.jpeg\" alt=\"enderdrache minecraft\" class=\"wp-image-20682\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/ender-dragon-minecraft-1024x546.jpeg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/ender-dragon-minecraft-300x160.jpeg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/ender-dragon-minecraft-768x410.jpeg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/ender-dragon-minecraft.jpeg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Minecraft-Drache-Feuerball\"><\/span>Minecraft Drache Feuerball<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/fireball-of-ender-dragon-minecraft.webp\" alt=\"Drache Feuerball\" class=\"wp-image-20694\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/fireball-of-ender-dragon-minecraft.webp 160w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/11\/fireball-of-ender-dragon-minecraft-150x150.webp 150w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><figcaption class=\"wp-element-caption\"><em>Ein Drachen-Feuerball<\/em><\/figcaption><\/figure><\/div>\n\n\n<p><strong>Drachen-Feuerkugeln<\/strong> sind spezielle Feuerkugeln, die der Enderdrache w\u00e4hrend seiner Bewegung abschie\u00dft. Im Gegensatz zu Ghast-Feuerkugeln k\u00f6nnen sie nicht abgelenkt werden und f\u00fcgen beim Aufprall keinen Schaden zu. Stattdessen legen sie Wolken aus violetten Effekten auf den Boden, die dem Spieler den gleichen Schaden zuf\u00fcgen wie ein anhaltender Schadenstrank der Stufe II.<\/p>\n\n\n\n<p>Das bedeutet, dass die <strong>Feuerb\u00e4lle des Enderdrachens<\/strong> magischen Schaden verursachen, der die Schadensreduzierung durch die R\u00fcstung des Spielers ignoriert. Allerdings wird der Schaden durch R\u00fcstungen, die von der Verzauberung Schutz profitieren, reduziert. Der Durchmesser des Wirkungsbereichs der violetten Wolke nimmt langsam zu, bis sie verschwindet.<\/p>\n\n\n\n<p>Wie bei der Attacke &#8220;Atem aus n\u00e4chster N\u00e4he&#8221; k\u00f6nnen lila Wolken gesammelt werden, um den Atem des Drachen zu erhalten.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;20707&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (1 vote)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Enderdrache Minecraft : Alles \u00fcber diese Kreatur&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (1 vote)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Enderdrache ist ein riesiger, fliegender, feindseliger Minecraft-Mob, den du findest, wenn du zum ersten Mal das End durch ein<\/p>\n","protected":false},"author":2,"featured_media":20702,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[43],"tags":[],"class_list":["post-20707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/20707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/comments?post=20707"}],"version-history":[{"count":4,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/20707\/revisions"}],"predecessor-version":[{"id":20771,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/posts\/20707\/revisions\/20771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/media\/20702"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/media?parent=20707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/categories?post=20707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/de\/wp-json\/wp\/v2\/tags?post=20707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}