{"id":14396,"date":"2022-07-02T08:16:21","date_gmt":"2022-07-02T06:16:21","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=14396"},"modified":"2022-07-02T08:16:25","modified_gmt":"2022-07-02T06:16:25","slug":"millones-de-fans-se-entristecen-por-la-muerte-del-youtuber-de-minecraft-technoblade-a-causa-del-cancer","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/es\/millones-de-fans-se-entristecen-por-la-muerte-del-youtuber-de-minecraft-technoblade-a-causa-del-cancer\/","title":{"rendered":"Millones de fans se entristecen por la muerte del YouTuber de Minecraft Technoblade a causa del c\u00e1ncer"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Technoblade, uno de los creadores de v\u00eddeos de Minecraft m\u00e1s populares en YouTube, ha fallecido tras un diagn\u00f3stico de c\u00e1ncer en fase 4, seg\u00fan su familia.<\/h2>\n\n\n\n<p>Technoblade ha muerto. El YouTuber de Minecraft, que luchaba contra un c\u00e1ncer en fase 4, revel\u00f3 su muerte en un v\u00eddeo publicado el jueves haciendo que su padre leyera una carta que escribi\u00f3 horas antes de morir. Technoblade ten\u00eda 23 a\u00f1os.<\/p>\n\n\n\n<p>&#8220;Si tuviera cien vidas m\u00e1s, creo que elegir\u00eda volver a ser Technoblade cada vez, porque fueron los a\u00f1os m\u00e1s felices de mi vida&#8221;, escribi\u00f3 en un mensaje a su comunidad unas ocho horas antes de su muerte.<\/p>\n\n\n\n<p>Su padre ley\u00f3 el mensaje en voz alta en un v\u00eddeo de YouTube el jueves titulado &#8220;so long nerds&#8221;, que lleg\u00f3 a millones de personas y alcanz\u00f3 el primer puesto en la p\u00e1gina de tendencias.<\/p>\n\n\n\n<p>&#8220;Espero que hay\u00e1is disfrutado de mi contenido y que os haya hecho re\u00edr a algunos, y espero que todos teng\u00e1is una vida larga, pr\u00f3spera y feliz porque os quiero&#8221;, escribi\u00f3 Technoblade en su mensaje.<\/p>\n\n\n\n<p>&#8220;Technoblade fuera&#8221;, dijo al final de la nota.<\/p>\n\n\n\n<p>La familia de Technoblade revel\u00f3 que su nombre de pila era Alex y comparti\u00f3 fotos de \u00e9l en el v\u00eddeo. Su familia no mencion\u00f3 su apellido y pidi\u00f3 que se protegiera su privacidad.<\/p>\n\n\n\n<p>Con m\u00e1s de 11 millones de seguidores en YouTube y casi 4 millones en Twitter, Technoblade atrajo a una gran comunidad de personas que disfrutaban de su humor, su amabilidad y sus juegos en Minecraft.<\/p>\n\n\n\n<p>&#8220;Era el ni\u00f1o m\u00e1s incre\u00edble que se pod\u00eda pedir&#8221;, dijo su padre en el v\u00eddeo, con l\u00e1grimas en los ojos.<\/p>\n\n\n\n<p>En parte de su mensaje, Technoblade agradeci\u00f3 a los que compraron su mercanc\u00eda y las suscripciones a su canal y explic\u00f3 que ahora sus hermanos podr\u00edan ir a la universidad si quer\u00edan.<\/p>\n\n\n\n<p>&#8220;Desde sus primeros d\u00edas en Internet, Technoblade siempre ha buscado formas de deleitar y recompensar a su p\u00fablico: regalando premios en l\u00ednea, fomentando el esp\u00edritu deportivo y, sobre todo, compartiendo sus aventuras en Minecraft para divertirse y re\u00edrse&#8221;, reza un comunicado de su familia al final del v\u00eddeo.<\/p>\n\n\n\n<p>La familia de Technoblade dijo que donar\u00eda una parte de los ingresos de los pedidos de productos en l\u00ednea a la Fundaci\u00f3n del Sarcoma de Am\u00e9rica.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"so long nerds\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/DPMluEVUqS0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>V\u00eddeo de despedida de Technoblade.<\/figcaption><\/figure>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.npr.org\/2022\/07\/01\/1109355414\/technoblade-minecraft-youtube-dies?t=1656741173918\" target=\"_blank\" rel=\"noreferrer noopener\">npr.org<\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;14396&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0 \\\/ 5 - (0 votos)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Millones de fans se entristecen por la muerte del YouTuber de Minecraft Technoblade a causa del c\u00e1ncer&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Technoblade, uno de los creadores de v\u00eddeos de Minecraft m\u00e1s populares en YouTube, ha fallecido tras un diagn\u00f3stico de c\u00e1ncer<\/p>\n","protected":false},"author":1,"featured_media":14390,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[45],"tags":[],"class_list":["post-14396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts\/14396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/comments?post=14396"}],"version-history":[{"count":1,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts\/14396\/revisions"}],"predecessor-version":[{"id":14397,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts\/14396\/revisions\/14397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/media\/14390"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/media?parent=14396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/categories?post=14396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/tags?post=14396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}