{"id":5173,"date":"2021-10-02T09:31:21","date_gmt":"2021-10-02T07:31:21","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=5173"},"modified":"2025-05-09T08:21:37","modified_gmt":"2025-05-09T06:21:37","slug":"decocraft-2-mod","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/","title":{"rendered":"Decocraft 2 &#8211; Mod &#8211; M\u00e1s bloques decorativos &#8211; 1.7.10 \u2192 1.12.2 \/ 1.20.1"},"content":{"rendered":"\n<p>Hay muchos bloques en Minecraft. Pero sigo pensando que los elementos de decoraci\u00f3n son bastante d\u00e9biles. Por qu\u00e9 no tenemos sillas de verdad y no escaleras, por qu\u00e9 no tenemos ba\u00f1eras de verdad, c\u00f3modas de verdad, frigor\u00edficos de verdad, etc.<\/p>\n\n\n\n<p>\u00a1 Y ah\u00ed es donde entra el <strong>mod Decocraft 2<\/strong> ! Producido por RazzleberryFox con la ayuda de Profmobius, a\u00f1ade m\u00e1s de 500 bloques puramente decorativos a Minecraft. Este mod ser\u00e1 un placer para todos los entusiastas de la arquitectura, ya sea de supervivencia o creativa, de un solo jugador o multijugador.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-06-20-30-39-731-1024x578.jpg\" alt=\"tabla de shaders\" class=\"wp-image-5051\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-06-20-30-39-731-1024x578.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-06-20-30-39-731-300x169.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-06-20-30-39-731-768x434.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-06-20-30-39-731.jpg 1360w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a9894b54e445\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9894b54e445\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Guia-del-usuario-de-Decocraft\" >Gu\u00eda del usuario de Decocraft<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Las-recetas-basicas\" >Las recetas b\u00e1sicas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Ejemplos-de-artesania\" >Ejemplos de artesan\u00eda<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Las-decoraciones-disponibles\" >Las decoraciones disponibles<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Decoracion-de-banos\" >Decoraci\u00f3n de ba\u00f1os<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Decoracion-de-la-habitacion\" >Decoraci\u00f3n de la habitaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Decoracion-de-mazmorras\" >Decoraci\u00f3n de mazmorras<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Decoracion-de-la-mesa-y-comida\" >Decoraci\u00f3n de la mesa y comida<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/minecraft-tutos.com\/es\/decocraft-2-mod\/#Descargar\" >Descargar<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Guia-del-usuario-de-Decocraft\"><\/span>Gu\u00eda del usuario de Decocraft<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A primera vista puede parecer complicado utilizar Decocraft, pero no es necesario consultar una Wiki o una Gu\u00eda durante horas. Con unos pocos elementos b\u00e1sicos puedes hacer simplemente todas tus decoraciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Las-recetas-basicas\"><\/span>Las recetas b\u00e1sicas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Para crear los bloques, necesitar\u00e1s la peque\u00f1a mesa de artesan\u00eda (justo arriba). Crearlo es bastante sencillo: necesitas una mesa de manualidades, un tinte verde, un tinte rojo y un lapisl\u00e1zuli.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"348\" height=\"328\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/craft.png\" alt=\"\" class=\"wp-image-5055\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/craft.png 348w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/craft-300x283.png 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/figure><\/div>\n\n\n<p>Despu\u00e9s de la elaboraci\u00f3n tendr\u00e1s que ir a la mesa, se abrir\u00e1 una interfaz. Cada objeto te pedir\u00e1 un n\u00famero determinado de arcilla, ya sea roja, azul o verde. Para introducirlos en la m\u00e1quina, tendr\u00e1s que colocarlos en la esquina superior izquierda y hacer clic en la peque\u00f1a flecha de abajo. Una vez hecho esto, los bloques crafteables tendr\u00e1n un recuadro m\u00e1s claro, s\u00f3lo tienes que pulsar sobre \u00e9l para empezar a craftearlos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"403\" height=\"444\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/illustration-1.png\" alt=\"\" class=\"wp-image-5059\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/illustration-1.png 403w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/illustration-1-272x300.png 272w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><\/figure><\/div>\n\n\n<p>Ahora te estar\u00e1s preguntando c\u00f3mo conseguir la arcilla para manualidades. Es muy sencillo, necesitas un bloque de tierra, un bloque de arena y el colorante adecuado dispuestos como abajo :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"385\" height=\"260\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/illustration-2.png\" alt=\"\" class=\"wp-image-5063\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/illustration-2.png 385w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/illustration-2-300x203.png 300w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ejemplos-de-artesania\"><\/span>Ejemplos de artesan\u00eda<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Una vez que tengas la arcilla para hacer manualidades, s\u00f3lo tienes que hacer tus decoraciones, aqu\u00ed tienes algunas recetas :<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bridge-560x315-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"315\" data-id=\"5070\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bridge-560x315-1.jpeg\" alt=\"puente\" class=\"wp-image-5070\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bridge-560x315-1.jpeg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bridge-560x315-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-room-560x315-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"315\" data-id=\"5074\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-room-560x315-1.jpeg\" alt=\"cama con dosel\" class=\"wp-image-5074\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-room-560x315-1.jpeg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-room-560x315-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-swing-560x315-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"315\" data-id=\"5078\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-swing-560x315-1.jpeg\" alt=\"columpio\" class=\"wp-image-5078\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-swing-560x315-1.jpeg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-swing-560x315-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-vanity-560x315-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"315\" data-id=\"5082\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-vanity-560x315-1.jpeg\" alt=\"vanity\" class=\"wp-image-5082\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-vanity-560x315-1.jpeg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-vanity-560x315-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p>Si todav\u00eda est\u00e1s confundido, mira el v\u00eddeo oficial de presentaci\u00f3n del mod :<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Decocraft Tutorial #1 The Basics\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/t_eofo2_RGE?start=68&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Las-decoraciones-disponibles\"><\/span>Las decoraciones disponibles<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es imposible mostrarte todas las decoraciones del mod Decocraft, a continuaci\u00f3n encontrar\u00e1s una peque\u00f1a parte de ellas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Decoracion-de-banos\"><\/span>Decoraci\u00f3n de ba\u00f1os<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-24-299-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5087\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-24-299-560x316-1.png\" alt=\"cepillo de dientes ba\u00f1o\" class=\"wp-image-5087\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-24-299-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-24-299-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-54-624-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5091\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-54-624-560x316-1.png\" alt=\"aseo del ba\u00f1o\" class=\"wp-image-5091\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-54-624-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-10-54-624-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-11-39-945-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5095\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-11-39-945-560x316-1.png\" alt=\"ducha del ba\u00f1o\" class=\"wp-image-5095\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-11-39-945-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-11-39-945-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bathroom-560x315-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"315\" data-id=\"5099\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bathroom-560x315-1.jpeg\" alt=\"armario de ba\u00f1o\" class=\"wp-image-5099\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bathroom-560x315-1.jpeg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-bathroom-560x315-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Decoracion-de-la-habitacion\"><\/span>Decoraci\u00f3n de la habitaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-23-745-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5109\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-23-745-560x316-1.png\" alt=\"room\" class=\"wp-image-5109\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-23-745-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-23-745-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-28-881-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5113\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-28-881-560x316-1.png\" alt=\"bedroom bedside table\" class=\"wp-image-5113\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-28-881-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-28-881-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-33-973-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5117\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-33-973-560x316-1.png\" alt=\"bedroom bed\" class=\"wp-image-5117\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-33-973-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-08-19-22-33-973-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-toys-560x315-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"315\" data-id=\"5121\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-toys-560x315-1.jpeg\" alt=\"toy room\" class=\"wp-image-5121\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-toys-560x315-1.jpeg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-toys-560x315-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Decoracion-de-mazmorras\"><\/span>Decoraci\u00f3n de mazmorras<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-33-193-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5126\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-33-193-560x316-1.png\" alt=\"canon dungeon\" class=\"wp-image-5126\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-33-193-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-33-193-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-43-429-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5130\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-43-429-560x316-1.png\" alt=\"skeleton dungeon\" class=\"wp-image-5130\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-43-429-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-43-429-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-49-550-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5134\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-49-550-560x316-1.png\" alt=\"giant spider web dungeon\" class=\"wp-image-5134\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-49-550-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-49-550-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-55-206-560x316-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5138\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-55-206-560x316-1.png\" alt=\"dungeon\" class=\"wp-image-5138\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-55-206-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-41-55-206-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Decoracion-de-la-mesa-y-comida\"><\/span>Decoraci\u00f3n de la mesa y comida<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5142\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-52-27-330-560x316-1.jpg\" alt=\"table stone\" class=\"wp-image-5142\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-52-27-330-560x316-1.jpg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-52-27-330-560x316-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5146\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-52-48-034-560x316-1.jpg\" alt=\"honey table\" class=\"wp-image-5146\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-52-48-034-560x316-1.jpg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-52-48-034-560x316-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-53-39-297-560x316-1.jpg\" alt=\"food table\" class=\"wp-image-5150\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-53-39-297-560x316-1.jpg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-53-39-297-560x316-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5154\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-54-12-430-560x316-1.png\" alt=\"grilled pig table\" class=\"wp-image-5154\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-54-12-430-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-54-12-430-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5158\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-58-43-001-560x316-1.png\" alt=\"carrot table\" class=\"wp-image-5158\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-58-43-001-560x316-1.png 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-58-43-001-560x316-1-300x169.png 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"316\" data-id=\"5162\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-59-18-977-560x316-1.jpg\" alt=\"ham table serano\" class=\"wp-image-5162\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-59-18-977-560x316-1.jpg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/javaw-2017-12-09-17-59-18-977-560x316-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"315\" data-id=\"5166\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-lounge-table-560x315-1.jpeg\" alt=\"prepared table\" class=\"wp-image-5166\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-lounge-table-560x315-1.jpeg 560w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/09\/decocraft-mod-minecraft-lounge-table-560x315-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Estos son s\u00f3lo algunos de los bloques disponibles en el mod. Puedes encontrar instrumentos musicales, elementos de cocina, elementos de sal\u00f3n, elementos de comedor, nuevas luces, puertas y ventanas, ordenadores, objetos cient\u00edficos, barricadas para tus casas, elementos de exterior como bancos y farolas, nuevas escaleras, juguetes, elementos deportivos como pelotas de boxeo, trofeos y muchas otras cosas.<\/p>\n\n\n\n<p>Este mod est\u00e1 realmente bien desarrollado, puedes pasar muchas horas construyendo con muchas posibilidades, \u00a1 dejo que lo veas por ti mismo !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Descargar\"><\/span>Descargar<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Elige la versi\u00f3n de Decocraft2 que quieres descargar :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/download\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [\u00daltima versi\u00f3n estable]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/files\/all?page=1&amp;pageSize=20&amp;version=1.20.1\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.20.1]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/files\/all?page=1&amp;pageSize=20&amp;version=1.19.4\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.19.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/download\/3347832\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.12.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/download\/2495134\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.11.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/download\/2484283\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.10.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/download\/2414537\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.9.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/download\/2404754\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.8.9]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\/download\/2404753\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Decocraft [1.7.10]<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\">\ud83d\udd28 Este mod requiere <a href=\"https:\/\/minecraft-tutos.com\/es\/minecraft-forge-descargar-e-instalar\/\">Minecraft Forge<\/a> y <a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/ptrlib\" target=\"_blank\" rel=\"noreferrer noopener\">PTRLib<\/a><br><a href=\"https:\/\/minecraft-tutos.com\/es\/como-instalar-un-mod-minecraft\/\">Descubre c\u00f3mo instalar un mod para Minecraft<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/decocraft\" target=\"_blank\" rel=\"noreferrer noopener\">\u2705Fuente<\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;5173&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (1 voto)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Decocraft 2 - Mod - M\u00e1s bloques decorativos - 1.7.10 \u2192 1.12.2 \\\/ 1.20.1&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hay muchos bloques en Minecraft. Pero sigo pensando que los elementos de decoraci\u00f3n son bastante d\u00e9biles. Por qu\u00e9 no tenemos<\/p>\n","protected":false},"author":2,"featured_media":5050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[20],"tags":[],"class_list":["post-5173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mod-es","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts\/5173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/comments?post=5173"}],"version-history":[{"count":5,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts\/5173\/revisions"}],"predecessor-version":[{"id":22062,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/posts\/5173\/revisions\/22062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/media\/5050"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/media?parent=5173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/categories?post=5173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/es\/wp-json\/wp\/v2\/tags?post=5173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}