{"id":11314,"date":"2022-03-17T19:05:27","date_gmt":"2022-03-17T18:05:27","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=11314"},"modified":"2025-05-10T08:52:44","modified_gmt":"2025-05-10T06:52:44","slug":"sodium-lithium-e-phosphor-3-mods-per-ottimizzare-minecraft","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/it\/sodium-lithium-e-phosphor-3-mods-per-ottimizzare-minecraft\/","title":{"rendered":"Sodium, Lithium e Phosphor &#8211; 3 mods per ottimizzare Minecraft &#8211; 1.15.2 \u2192 1.21.5"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Sodium, Lithium e Phosphor sono tre mod che lavorano con la Fabric API con l&#8217;obiettivo finale di ottimizzare Minecraft meglio di OptiFine.<\/h2>\n\n\n\n<p>Qualsiasi giocatore che non fa girare Minecraft sul PC di un giocatore sa che ottimizzare Minecraft non \u00e8 un compito facile. Se avete gi\u00e0 provato mods come <a href=\"https:\/\/minecraft-tutos.com\/it\/optifine-scaricare-e-installare\/\">OptiFine<\/a>, Better FPS o FPS Reducer senza successo, allora <strong>Phosphor, Sodium e Lithium<\/strong> potrebbero fare al caso vostro.<\/p>\n\n\n\n<p>Queste tre <a href=\"https:\/\/minecraft-tutos.com\/it\/category\/mod-it\/\">mod<\/a>, create da jellysquid, mirano ciascuna a una specifica ottimizzazione di Minecraft e richiedono l&#8217;uso delle API Fabric. Funzionano meglio insieme, ma se siete riusciti a determinare una specifica area di miglioramento, potreste decidere di installarne solo due o anche una.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a042ae3ac399\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a042ae3ac399\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/it\/sodium-lithium-e-phosphor-3-mods-per-ottimizzare-minecraft\/#Sodium-Minecraft\" >Sodium Minecraft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/it\/sodium-lithium-e-phosphor-3-mods-per-ottimizzare-minecraft\/#Lithium-Minecraft\" >Lithium Minecraft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/it\/sodium-lithium-e-phosphor-3-mods-per-ottimizzare-minecraft\/#Phosphor-Minecraft\" >Phosphor Minecraft<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/it\/sodium-lithium-e-phosphor-3-mods-per-ottimizzare-minecraft\/#Scarica-Sodium-Lithium-e-Phosphor\" >Scarica Sodium, Lithium e Phosphor<\/a><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sodium-Minecraft\"><\/span>Sodium Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/logo-sodium-minecraft-150x150-1.jpeg\" alt=\"Sodium Minecraft\" class=\"wp-image-11274\" title=\"\"><figcaption class=\"wp-element-caption\">Sodium Minecraft<\/figcaption><\/figure><\/div>\n\n\n<p><strong>Sodium<\/strong> sostituisce il renderer di Minecraft e migliora drasticamente il frame-rate, riduce il micro-stutter e risolve i problemi grafici. Offre grande compatibilit\u00e0 con l&#8217;ecosistema di mods Fabric e non compromette l&#8217;aspetto del gioco<\/p>\n\n\n\n<p>Sodium e Optifine sono incompatibili tra loro. Dovete sceglierne uno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"600\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/sodium-minecraft.jpeg\" alt=\"grafica di minecraft ottimizzata con sodium\" class=\"wp-image-11280\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/sodium-minecraft.jpeg 920w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/sodium-minecraft-300x196.jpeg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/sodium-minecraft-768x501.jpeg 768w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><figcaption class=\"wp-element-caption\"><em>Confronto FPS tra Minecraft vanilla e <strong>Sodium<\/strong> a una distanza di rendering di 32 <a href=\"https:\/\/minecraft-tutos.com\/it\/chunks-in-minecraft-cosa-sono-come-si-possono-visualizzare-e-che-dimensioni-hanno\/\">chunks<\/a>.<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Lithium-Minecraft\"><\/span>Lithium Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/logo-lithium-minecraft-150x150-1.jpeg\" alt=\"Lithium Minecraft\" class=\"wp-image-11286\" title=\"\"><figcaption class=\"wp-element-caption\">Lithium Minecraft<\/figcaption><\/figure><\/div>\n\n\n<p><strong>Lithium<\/strong> \u00e8 una mod di ottimizzazione pi\u00f9 generale per Minecraft che permette di migliorare un certo numero di sistemi (fisica del gioco, IA delle creature, ticchettio dei blocchi, ecc) senza cambiare il comportamento.<\/p>\n\n\n\n<p>Funziona sia sul client che sul server, e pu\u00f2 essere installato sui server senza richiedere che anche i client abbiano il mod. Una volta che il mod \u00e8 installato, si pu\u00f2 vedere un miglioramento medio del 45% nei tempi di esecuzione del server, che si traduce in un gioco molto pi\u00f9 leggero.<\/p>\n\n\n\n<p>Anche in modalit\u00e0 single-player, il gioco esegue un &#8220;server incorporato&#8221; che controlla il mondo in cui si trova il giocatore. Ottimizzando l&#8217;angolo del server del gioco, \u00e8 possibile liberare la CPU del computer per concentrarsi su altri compiti, migliorando il frame rate e la reattivit\u00e0. Per i server multiplayer, gli amministratori possono aspettarsi un drammatico miglioramento dei tempi di spunta, permettendo al loro hardware di supportare pi\u00f9 entit\u00e0, pezzi e giocatori caricati.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"261\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/lithium-minecraft-1024x261.png\" alt=\"grafica del server di minecraft ottimizzata con il lithium\" class=\"wp-image-11292\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/lithium-minecraft-1024x261.png 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/lithium-minecraft-300x76.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/lithium-minecraft-768x195.png 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/lithium-minecraft.png 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Grafico del tempo di tick del server (mspt) prima e dopo l&#8217;installazione di <strong>Lithium<\/strong>. Misurazioni effettuate in un mondo esistente ad una distanza di rendering di 18.<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Phosphor-Minecraft\"><\/span>Phosphor Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/logo-phosphor-minecraft-150x150-1.jpeg\" alt=\"Phosphor Minecraft\" class=\"wp-image-11298\" title=\"\"><figcaption class=\"wp-element-caption\">Phosphor Minecraft<\/figcaption><\/figure><\/div>\n\n\n<p><strong>Phosphor<\/strong> \u00e8 un mod che mira a ottimizzare una delle aree pi\u00f9 inefficienti del gioco : il motore di illuminazione. Funziona sia sul client che sul server, e pu\u00f2 essere installato sui server senza richiedere che anche i client abbiano il mod.<\/p>\n\n\n\n<p>Con Phosphor, il tempo necessario al gioco per generare pezzi pu\u00f2 essere dimezzato per certe dimensioni, e il frame lag quando si attraversa il mondo pu\u00f2 essere drasticamente ridotto. Questa \u00e8 una soluzione senza compromessi per migliorare le prestazioni, sia in modalit\u00e0 giocatore singolo che su grandi server multiplayer, e non cambia nessuna delle caratteristiche o comportamenti del gioco originale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"761\" height=\"293\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/phosphor-minecraft.jpeg\" alt=\"grafica minecraft ottimizzata con phosphor\" class=\"wp-image-11304\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/phosphor-minecraft.jpeg 761w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2022\/03\/phosphor-minecraft-300x116.jpeg 300w\" sizes=\"auto, (max-width: 761px) 100vw, 761px\" \/><figcaption class=\"wp-element-caption\"><em>Grafico che confronta il tempo trascorso ad illuminare le sezioni tra la versione vanilla di Minecraft e diverse versioni di <strong>Phosphor<\/strong>.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Scarica-Sodium-Lithium-e-Phosphor\"><\/span>Scarica Sodium, Lithium e Phosphor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Per utilizzare queste mods \u00e8 necessario scaricare l&#8217;ultima versione di <a href=\"https:\/\/minecraft-tutos.com\/it\/fabric-api-modloader\/\">Fabric<\/a>. Segui i link qui sotto per scaricare le mods :<\/p>\n\n\n\n<ul id=\"block-7e3b3dce-1c27-48a4-b81c-7a3425b57af9\" class=\"wp-block-list\">\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\" target=\"_blank\" rel=\"noopener\">Phosphor [ultima versione]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5 <a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\/3832074\" target=\"_blank\" rel=\"noopener\">Phosphor [1.19.4]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\/3573395\" target=\"_blank\" rel=\"noopener\">Phosphor [1.18.2]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\/3537802\" target=\"_blank\" rel=\"noopener\">Phosphor [1.17.1]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\/3537800\" target=\"_blank\" rel=\"noopener\">Phosphor [1.16.5]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\/2918761\" target=\"_blank\" rel=\"noopener\">Phosphor [1.15.2]<\/a><\/li>\n<\/ul>\n\n\n\n<ul id=\"block-c15197e7-25be-4713-93d4-895298b7601c\" class=\"wp-block-list\">\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/modrinth.com\/mod\/lithium\/versions\" target=\"_blank\" rel=\"noreferrer noopener\">Lithium [ultima versione]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5\u00a0<a href=\"https:\/\/modrinth.com\/mod\/lithium\/versions?g=1.21.5\" target=\"_blank\" rel=\"noreferrer noopener\">Lithium [1.21.5]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5\u00a0<a href=\"https:\/\/cdn.modrinth.com\/data\/gvQqBUqZ\/versions\/bAbb09VF\/lithium-fabric-mc1.20.6-0.12.3.jar\" target=\"_blank\" rel=\"noopener\">Lithium [1.20.6]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5 <a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/lithium\/download\/4439705\" target=\"_blank\" rel=\"noopener\">Lithium [1.19.4]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/lithium\/download\/3670312\" target=\"_blank\" rel=\"noopener\">Lithium [1.18.2]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/lithium\/download\/3438799\" target=\"_blank\" rel=\"noopener\">Lithium [1.17.1]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\/3294303\" target=\"_blank\" rel=\"noopener\">Lithium [1.16.5]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\/download\/2918761\" target=\"_blank\" rel=\"noopener\">Lithium [1.15.2]<\/a><\/li>\n<\/ul>\n\n\n\n<ul id=\"block-3de88ced-cf6c-48f9-9927-4f56b1214c6a\" class=\"wp-block-list\">\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/modrinth.com\/mod\/sodium\/versions\" target=\"_blank\" rel=\"noreferrer noopener\">Sodium [ultima versione]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5\u00a0<a href=\"https:\/\/modrinth.com\/mod\/sodium\/versions?g=1.21.5\" target=\"_blank\" rel=\"noreferrer noopener\">Sodium [1.21.5]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5\u00a0<a href=\"https:\/\/cdn.modrinth.com\/data\/AANobbMI\/versions\/IZskON6d\/sodium-fabric-0.5.8%2Bmc1.20.6.jar\" target=\"_blank\" rel=\"noopener\">Sodium [1.20.6]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5 <a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/sodium\/download\/4437119\" target=\"_blank\" rel=\"noopener\">Sodium [1.19.4]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/sodium\/download\/3669187\" target=\"_blank\" rel=\"noopener\">Sodium [1.18.2]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/sodium\/download\/3605275\" target=\"_blank\" rel=\"noopener\">Sodium [1.17.1]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/sodium\/download\/3067101\" target=\"_blank\" rel=\"noopener\">Sodium [1.16.5]<\/a><\/li>\n<\/ul>\n\n\n\n<p>\u2705 Fonte dei mods su Curseforge :&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/phosphor\" target=\"_blank\" rel=\"noreferrer noopener\">Phosphor<\/a>&nbsp;\u2013&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/lithium\" target=\"_blank\" rel=\"noreferrer noopener\">Lithium<\/a>&nbsp;\u2013&nbsp;<a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/sodium\/files\" target=\"_blank\" rel=\"noreferrer noopener\">Sodium<\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;11314&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (1 vote)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Sodium, Lithium e Phosphor - 3 mods per ottimizzare Minecraft - 1.15.2 \u2192 1.21.5&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (1 vote)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sodium, Lithium e Phosphor sono tre mod che lavorano con la Fabric API con l&#8217;obiettivo finale di ottimizzare Minecraft meglio<\/p>\n","protected":false},"author":2,"featured_media":11270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[105,234,258],"tags":[],"class_list":["post-11314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mod-it","category-1-19","category-1-20","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/11314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/comments?post=11314"}],"version-history":[{"count":15,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/11314\/revisions"}],"predecessor-version":[{"id":22146,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/11314\/revisions\/22146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/media\/11270"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/media?parent=11314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/categories?post=11314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/tags?post=11314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}