{"id":19803,"date":"2023-10-29T08:26:55","date_gmt":"2023-10-29T07:26:55","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=19803"},"modified":"2023-10-29T08:26:57","modified_gmt":"2023-10-29T07:26:57","slug":"minecraft-bundle-come-crearne-e-usarne-uno","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/it\/minecraft-bundle-come-crearne-e-usarne-uno\/","title":{"rendered":"Minecraft Bundle : come crearne e usarne uno ?"},"content":{"rendered":"\n<p><strong>Una borsa in Minecraft<\/strong>&nbsp;\u00e8 un oggetto che pu\u00f2 contenere pi\u00f9 oggetti di tipo diverso in un\u2019unica posizione dell\u2019inventario.<\/p>\n\n\n\n<p>Nota bene : questo contenuto \u00e8 apparso nelle versioni di sviluppo dell\u2019edizione Java, ma l\u2019aggiornamento completo che lo contiene non \u00e8 ancora stato rilasciato. La borsa dovrebbe arrivare in un futuro&nbsp;<a href=\"https:\/\/minecraft-tutos.com\/it\/category\/aggiornamento\/\">aggiornamento di Minecraft<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/bag-minecraft.webp\" alt=\"borsa vuota di minecraft\" class=\"wp-image-19759\" title=\"Minecraft Bundle: come crearne e usarne uno ? 2\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/bag-minecraft.webp 160w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/bag-minecraft-150x150.webp 150w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><figcaption class=\"wp-element-caption\"><em>Una borsa vuota.<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Gli oggetti che si impilano fino a 16 occupano pi\u00f9 spazio nella borsa, mentre gli oggetti che non si impilano occupano tutta la borsa senza lasciare spazio ad altri oggetti.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/bag-minecraft-1.webp\" alt=\"sacchetto pieno minecraft\" class=\"wp-image-19765\" title=\"Minecraft Bundle: come crearne e usarne uno ? 3\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/bag-minecraft-1.webp 160w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/bag-minecraft-1-150x150.webp 150w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><figcaption class=\"wp-element-caption\"><em>Un sacchetto pieno.<\/em><\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Fabbricazione<\/h2>\n\n\n\n<p><strong>Per creare un sacchetto<\/strong>, dovrete usare le vostre abilit\u00e0 di caccia per trovare gli ingredienti necessari. Avrete bisogno di 6 pelli di coniglio e 2 corde.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/craft-bag-minecraft.png\" alt=\"fare una borsa in minecraft\" class=\"wp-image-19771\" width=\"359\" height=\"206\" title=\"Minecraft Bundle: come crearne e usarne uno ? 4\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/craft-bag-minecraft.png 647w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/craft-bag-minecraft-300x172.png 300w\" sizes=\"auto, (max-width: 359px) 100vw, 359px\" \/><figcaption class=\"wp-element-caption\"><em>Creare una borsa in Minecraft<\/em><\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Utilizzare<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/inventar-bag-minecraft.png\" alt=\"inventario borsa minecraft\" class=\"wp-image-19777\" width=\"213\" height=\"212\" title=\"Minecraft Bundle: come crearne e usarne uno ? 5\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/inventar-bag-minecraft.png 333w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/inventar-bag-minecraft-300x298.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/inventar-bag-minecraft-150x150.png 150w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><figcaption class=\"wp-element-caption\"><em>La dimensione degli oggetti impilati (linea superiore) e il numero di slot del sacchetto che occupano (linea centrale). I bastoni si impilano fino a 64, quindi occupano uno slot del sacchetto; le perline finali si impilano fino a 16, quindi ne occupano quattro; le spade non si impilano, quindi occupano l\u2019intero pacchetto. Quindi, ad esempio, un sacchetto pu\u00f2 contenere 32 bastoni e 8 perline finali (in basso), che occupano un totale di (32\u00d71)+(8\u00d74)=64 slot del sacchetto.<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>I sacchetti vengono utilizzati per conservare diversi tipi di oggetti nello stesso slot dell\u2019inventario. Questo non aumenta la capacit\u00e0 totale dello slot : ogni borsa ha 64 \u201cslot di borsa\u201d, e ogni oggetto inserito nella borsa occupa questi slot nello stesso modo in cui occupa lo spazio in un normale slot d\u2019inventario : gli oggetti che si impilano fino a 64 occupano 1 slot di borsa, gli oggetti che si impilano fino a 16 (come le uova) ne occupano 4, e gli oggetti che non si impilano (come strumenti\/armi\/armature) occupano l\u2019intera borsa, tutti e 64 gli slot.<\/p>\n\n\n\n<p>Anche se i sacchetti non possono essere impilati, un sacchetto pu\u00f2 essere inserito all\u2019interno di un altro (annidato) : il sacchetto interno utilizza 4 slot, pi\u00f9 il numero di slot gi\u00e0 occupati dagli oggetti in quel sacchetto.<\/p>\n\n\n\n<p>Per inserire gli oggetti all\u2019interno di un sacchetto, prendere il sacchetto dall\u2019inventario e fare clic con il tasto destro del mouse sull\u2019oggetto o sugli oggetti che si desidera inserire all\u2019interno, oppure prendere l\u2019oggetto o gli oggetti e fare clic con il tasto destro del mouse sul sacchetto. Quando si inserisce un sacchetto all\u2019interno di un altro sacchetto, l\u2019interfaccia utilizza il primo metodo : prendendo il sacchetto A e facendo clic con il pulsante destro del mouse sul sacchetto B, si cercher\u00e0 di inserire il sacchetto B all\u2019interno di A.<\/p>\n\n\n\n<p>Le borse possono essere utilizzate nell\u2019inventario per rimuovere l\u2019ultimo oggetto inserito al loro interno. In questo modo, \u00e8 possibile accedere agli oggetti LIFO (last in, first out). Quando viene utilizzato al di fuori dell\u2019inventario, scarica tutti gli oggetti nel mondo.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Passando con il mouse sopra la borsa, si possono vedere gli oggetti contenuti negli slot dell\u2019inventario. Il numero di slot utilizzati dalla borsa viene visualizzato come \/64 nel tooltip. Quando la borsa \u00e8 piena, gli slot vuoti sono ombreggiati di uno.<video controls=\"\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/10\/bundle-minecraft.mp4\"><\/video><em>Come funziona la borsa in Minecraft.<\/em><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;19803&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (1 vote)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Minecraft Bundle : come crearne e usarne uno ?&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (1 vote)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una borsa in Minecraft&nbsp;\u00e8 un oggetto che pu\u00f2 contenere pi\u00f9 oggetti di tipo diverso in un\u2019unica posizione dell\u2019inventario. Nota bene<\/p>\n","protected":false},"author":2,"featured_media":19793,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[100],"tags":[],"class_list":["post-19803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-come","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/19803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/comments?post=19803"}],"version-history":[{"count":3,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/19803\/revisions"}],"predecessor-version":[{"id":19888,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/19803\/revisions\/19888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/media\/19793"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/media?parent=19803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/categories?post=19803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/tags?post=19803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}