{"id":5589,"date":"2021-09-29T16:22:44","date_gmt":"2021-09-29T14:22:44","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=5589"},"modified":"2025-11-23T10:35:40","modified_gmt":"2025-11-23T09:35:40","slug":"xray-mod-minecraft","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/","title":{"rendered":"Xray Mod Minecraft &#8211; 1.7.10 \u2192 1.21.11"},"content":{"rendered":"\n<p>La <strong>Xray mod<\/strong> \u00e8 una <a href=\"https:\/\/minecraft-tutos.com\/it\/category\/mod-it\/\">mod per Minecraft<\/a> che permette di vedere attraverso i blocchi inutili, come terra, pietra, erba e sabbia per far apparire solo i minerali ricercati dal giocatore come diamante, oro, ferro, carbone.<\/p>\n\n\n\n<p>Il mod mostra anche dungeon, casse e altri oggetti fatti dai giocatori come porte o scale.<\/p>\n\n\n\n<p>Questo mod funziona in solo, ma anche in multiplayer su server non protetti. Per gli amministratori di server, potete proteggere il vostro server usando il <a href=\"https:\/\/dev.bukkit.org\/projects\/anti-x-ray\" target=\"_blank\" rel=\"noreferrer noopener\">plugin anti-xray.<\/a><\/p>\n\n\n\n<p>Attenzione: questo mod xray per Minecraft \u00e8 vietato su tutti i server multiplayer, se lo usate in multiplayer, potreste essere bannati.<\/p>\n\n\n\n<p>Raccomandiamo l&#8217;uso <a href=\"https:\/\/minecraft-tutos.com\/it\/xray-ultimate-texture-pack-minecraft\/\">dell&#8217;Xray Ultimate texture pack<\/a> piuttosto che questa minecraft xray mod.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a989b818f0bc\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a989b818f0bc\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Illustrazioni\" >Illustrazioni<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Scaricare-Xray-mod-per-Minecraft\" >Scaricare Xray mod per Minecraft<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Xray-per-Forge\" >Xray per Forge<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Xray-per-Fabric\" >Xray per Fabric<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Xray-senza-Forge\" >Xray senza Forge<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Installare-il-mod-Xray-senza-Forge\" >Installare il mod Xray senza Forge<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Xray-mod-con-Vanilla-Launcher\" >Xray mod con Vanilla Launcher<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Scarica-il-file-che-corrisponde-alla-tua-versione-di-Minecraft\" >Scarica il file che corrisponde alla tua versione di Minecraft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Fate-doppio-clic-su-questo-file-e-dovrebbe-apparire-una-finestra-pop-up\" >Fate doppio clic su questo file e dovrebbe apparire una finestra pop-up<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Nella-finestra-successiva-avete-la-possibilita-di-dare-un-nome-allinstallazione\" >Nella finestra successiva, avete la possibilit\u00e0 di dare un nome all&#8217;installazione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Avviare-il-lanciatore-di-Minecraft\" >Avviare il lanciatore di Minecraft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Una-volta-che-il-gioco-e-in-esecuzione-si-puo-cliccare-su-Opzioni%3E-Controlli-e-scorrere-verso-il-basso-fino-a-vedere-una-sezione-%E2%80%9CXRay%E2%80%9D\" >Una volta che il gioco \u00e8 in esecuzione, si pu\u00f2 cliccare su [Opzioni]&gt; [Controlli] e scorrere verso il basso fino a vedere una sezione &#8220;XRay&#8221;.<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Xray-mod-con-Optifine\" >Xray mod con Optifine<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#Domande-Risposte-sul-Mod-Xray\" >Domande \/ Risposte sul Mod Xray<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#%E2%9D%93-A-cosa-serve-il-mod-Xray\" >\u2753 A cosa serve il mod Xray?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#%F0%9F%92%BF-Con-quali-versioni-di-Minecraft-e-compatibile-il-mod-Xray\" >\ud83d\udcbf Con quali versioni di Minecraft \u00e8 compatibile il mod Xray?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/minecraft-tutos.com\/it\/xray-mod-minecraft\/#%E2%9A%99%EF%B8%8F-Il-mod-Xray-e-compatibile-con-Forge\" >\u2699\ufe0f Il mod Xray \u00e8 compatibile con Forge?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Illustrazioni\"><\/span>Illustrazioni<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ecco un&#8217;anteprima del risultato :<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-minecraft-1-1024x549.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" data-id=\"2011\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-minecraft-1-1024x549.jpg\" alt=\"\" class=\"wp-image-2011\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-minecraft-1-1024x549.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-minecraft-1-300x161.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-minecraft-1-768x411.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-minecraft-1-1536x823.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-minecraft-1.jpg 1680w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/Xray-mod-minecraft-2-1024x549.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" data-id=\"2016\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/Xray-mod-minecraft-2-1024x549.jpg\" alt=\"\" class=\"wp-image-2016\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/Xray-mod-minecraft-2-1024x549.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/Xray-mod-minecraft-2-300x161.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/Xray-mod-minecraft-2-768x411.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/Xray-mod-minecraft-2-1536x823.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/Xray-mod-minecraft-2.jpg 1680w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"877\" height=\"534\" data-id=\"2020\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-3.jpg\" alt=\"\" class=\"wp-image-2020\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-3.jpg 877w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-3-300x183.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-3-768x468.jpg 768w\" sizes=\"auto, (max-width: 877px) 100vw, 877px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"891\" height=\"541\" data-id=\"2024\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-4.jpg\" alt=\"\" class=\"wp-image-2024\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-4.jpg 891w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-4-300x182.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-4-768x466.jpg 768w\" sizes=\"auto, (max-width: 891px) 100vw, 891px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-redstone.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"535\" data-id=\"2028\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-redstone.jpg\" alt=\"\" class=\"wp-image-2028\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-redstone.jpg 886w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-redstone-300x181.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-redstone-768x464.jpg 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-luminosite.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"889\" height=\"544\" data-id=\"2032\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-luminosite.jpg\" alt=\"\" class=\"wp-image-2032\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-luminosite.jpg 889w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-luminosite-300x184.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-luminosite-768x470.jpg 768w\" sizes=\"auto, (max-width: 889px) 100vw, 889px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-menu.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"881\" height=\"530\" data-id=\"2036\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-menu.jpg\" alt=\"\" class=\"wp-image-2036\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-menu.jpg 881w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-menu-300x180.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-minecraft-mod-menu-768x462.jpg 768w\" sizes=\"auto, (max-width: 881px) 100vw, 881px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-dans-minecraft-5-1024x542.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" data-id=\"2040\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-dans-minecraft-5-1024x542.jpg\" alt=\"\" class=\"wp-image-2040\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-dans-minecraft-5-1024x542.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-dans-minecraft-5-300x159.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-dans-minecraft-5-768x407.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-dans-minecraft-5-1536x814.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-dans-minecraft-5.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-visu-bloc-1024x542.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" data-id=\"2044\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-visu-bloc-1024x542.jpg\" alt=\"\" class=\"wp-image-2044\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-visu-bloc-1024x542.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-visu-bloc-300x159.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-visu-bloc-768x407.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-visu-bloc-1536x814.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-visu-bloc.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-blocs-1024x542.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" data-id=\"2048\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-blocs-1024x542.jpg\" alt=\"\" class=\"wp-image-2048\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-blocs-1024x542.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-blocs-300x159.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-blocs-768x407.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-blocs-1536x814.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-blocs.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-edit-block-1024x542.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" data-id=\"2052\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-edit-block-1024x542.jpg\" alt=\"\" class=\"wp-image-2052\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-edit-block-1024x542.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-edit-block-300x159.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-edit-block-768x407.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-edit-block-1536x814.jpg 1536w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/xray-mod-edit-block.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Scaricare-Xray-mod-per-Minecraft\"><\/span>Scaricare Xray mod per Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ci sono 3 versioni del mod Xray, una che funziona senza API (e quindi non \u00e8 compatibile con altri mod), un&#8217;altra che funziona con Minecraft Forge e l&#8217;ultima che richiede Fabric per Minecraft.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Xray-per-Forge\"><\/span>Xray per Forge<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/files\/all?page=1&amp;pageSize=20&amp;showAlphaFiles=hide\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 NeoForge [1.21.11]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/4941553\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.20.6]<\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3712732\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3712732\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3905392\" target=\"_blank\" rel=\"noopener\"><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/4470159\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod &#8211; Forge [1.19.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3712732\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3712732\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3712732\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod &#8211; Forge [1.18.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3654353\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod &#8211; Forge [1.17.1]<\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" aria-label=\"\ud83d\udce5 Xray Mod \u2013 Forge [1.16.5] (opens in a new tab)\" href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3205011\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.16.5]<\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/3105604\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.16.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2876885\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.15.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2884927\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.14.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2750239\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.12.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2461192\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.11.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2450596\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.10.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2362623\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.9.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2371872\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.8.9]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray\/download\/2362622\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod \u2013 Forge [1.7.10]<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Xray-per-Fabric\"><\/span>Xray per Fabric<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul id=\"block-cda14e97-3e15-4226-bb69-4941c76fc34b\" class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/download\/6534801\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod &#8211; Fabric [1.21.5]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/files\/all?page=1&amp;pageSize=20&amp;version=1.21&amp;gameVersionTypeId=4\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod \u2013 Fabric [1.21.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/legacy.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/download\/5328354\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod \u2013 Fabric [1.20.6]<\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/download\/3828928\" target=\"_blank\" rel=\"noopener\"><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/download\/4470150\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod &#8211; Fabric [1.19.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/download\/3717327\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod &#8211; Fabric [1.18.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/download\/3349248\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod &#8211; Fabric [1.17.1]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/mc-mods\/advanced-xray-fabric-edition\/download\/3197176\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod &#8211; Fabric [1.16.5]<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Xray-senza-Forge\"><\/span>Xray senza Forge<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.mediafire.com\/file\/iwcxsjzp3dnstiq\/xray-75-1215.jar\/file\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod [1.21.5]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.mediafire.com\/file\/vu3oapc2c7kt8mn\/xray-74-1206.jar\/file\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod [1.20.6]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.mediafire.com\/file\/4be99s24yj80a4n\/xray-73-119.jar\/file\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Xray Mod [1.19.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.mediafire.com\/file\/jct4hwb8jh9eu94\/xray-73-1182.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod [1.18.2]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5<a href=\"https:\/\/www.mediafire.com\/file\/tlmv1rbslns22rt\/xray-73-1171.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\"> Xray Mod [1.17.1]<\/a><\/li>\n\n\n\n<li>\ud83d\udce5 <a href=\"https:\/\/www.mediafire.com\/file\/k1476jysrlzl268\/xray-72-1165.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\">Xray Mod [1.16.5]<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.mediafire.com\/file\/omwmxzfpp1ruahw\/xray-68-1152.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod [1.15.2]<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.mediafire.com\/file\/76sgged20j9zkn0\/xray-67-1144.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod [1.14.4]<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.mediafire.com\/file\/mfxm733n3u5n33t\/XRay-63-1132.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod [1.13.2]<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.mediafire.com\/file\/026nf2o0zazy5i8\/XRay-63-1122.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod [1.12.2]<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.mediafire.com\/file\/wuue768bar6s3x2\/XRay-58.jar\/file\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Xray Mod [1.7.10 a 1.12.1]<\/a><\/li>\n\n\n\n<li><a aria-label=\"History of all versions (opens in a new tab)\" class=\"rank-math-link\" href=\"https:\/\/www.mediafire.com\/folder\/5v6x64zl4irqq\/xray\" target=\"_blank\" rel=\"noreferrer noopener\">Storia di tutte le versioni<\/a><\/li>\n<\/ul>\n\n\n\n<p>\u26a0\ufe0f Si prega di notare che questa versione del mod Xray NON \u00e8 COMPATIBILE con ALCUN tipo di Mod Loader come Forge, Rift o Fabric &#8211; questo significa che \u00e8 possibile utilizzare Xray solo da solo e non con altri mod.<\/p>\n\n\n\n<p>Questo \u00e8 dovuto principalmente al modo in cui il mod Xray \u00e8 installato nel codice base di Minecraft, i Modloarders usano diverse tecniche di codifica per installare i mod in conflitto con il metodo Xray.<\/p>\n\n\n\n<p>L&#8217;attuale sviluppatore ha dichiarato che indagher\u00e0 sulla possibilit\u00e0 di &#8220;compatibilit\u00e0 del modloader&#8221;, ma non ci sono informazioni su quanto tempo questo potrebbe richiedere.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Installare-il-mod-Xray-senza-Forge\"><\/span>Installare il mod Xray senza Forge<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Potete installare il mod in vanilla mod o con <a href=\"https:\/\/minecraft-tutos.com\/it\/optifine-scaricare-e-installare\/\">Optifine<\/a>. <a href=\"https:\/\/minecraft-tutos.com\/it\/come-installare-un-mod-di-minecraft\/\">Come installare le mod in Minecraft ?<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Xray-mod-con-Vanilla-Launcher\"><\/span>Xray mod con Vanilla Launcher<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n<div id=\"rank-math-howto\" class=\"rank-math-block\">\n<div class=\"rank-math-howto-description\">\n\n<p> Come installare il mod Xray con il launcher vanilla di Minecraft <\/p>\n\n<\/div>\n<p class=\"rank-math-howto-duration\"><strong>Tempo totale:<\/strong> <span>3 minuti<\/span><\/p>\n<ol class=\"rank-math-steps \">\n<li id=\"howto-step-1610875151376\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Scarica-il-file-che-corrisponde-alla-tua-versione-di-Minecraft\"><\/span>Scarica il file che corrisponde alla tua versione di Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><img loading=\"lazy\" decoding=\"async\" width=\"76\" height=\"86\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/install-mod-xray-launcher-java-1.jpg\" class=\"attachment-full size-full\" alt=\"\" title=\"\"><p>Avrete un file .jar che potrete salvare dove volete.<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1610875201155\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Fate-doppio-clic-su-questo-file-e-dovrebbe-apparire-una-finestra-pop-up\"><\/span>Fate doppio clic su questo file e dovrebbe apparire una finestra pop-up<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><img loading=\"lazy\" decoding=\"async\" width=\"264\" height=\"127\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/install-mod-xray-clic.jpg\" class=\"attachment-full size-full\" alt=\"\" title=\"\"><p>L&#8217;elenco a discesa mostra tutte le versioni di Minecraft che hai attualmente installato. Clicca sul pulsante [Installa].<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1610875228486\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Nella-finestra-successiva-avete-la-possibilita-di-dare-un-nome-allinstallazione\"><\/span>Nella finestra successiva, avete la possibilit\u00e0 di dare un nome all&#8217;installazione<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"148\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/install-mod-xray-nom.jpg\" class=\"attachment-full size-full\" alt=\"\" title=\"\"><p>Si pu\u00f2 lasciare l&#8217;impostazione predefinita &#8216;{versione n.}-Xray&#8217;. Premere [OK].<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1610875250690\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Avviare-il-lanciatore-di-Minecraft\"><\/span>Avviare il lanciatore di Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><img loading=\"lazy\" decoding=\"async\" width=\"1056\" height=\"682\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/install-mod-xray-launcher-vanilla.jpg\" class=\"attachment-full size-full\" alt=\"\" title=\"\"><p>Accanto al grande pulsante verde [PLAY], dovresti essere in grado di selezionare l&#8217;installazione Xray appena creata.<\/p>\n<\/div>\n<\/li>\n<li id=\"howto-step-1610875321119\" class=\"rank-math-step\">\n<h3 class=\"rank-math-step-title \"><span class=\"ez-toc-section\" id=\"Una-volta-che-il-gioco-e-in-esecuzione-si-puo-cliccare-su-Opzioni%3E-Controlli-e-scorrere-verso-il-basso-fino-a-vedere-una-sezione-%E2%80%9CXRay%E2%80%9D\"><\/span>Una volta che il gioco \u00e8 in esecuzione, si pu\u00f2 cliccare su [Opzioni]&gt; [Controlli] e scorrere verso il basso fino a vedere una sezione &#8220;XRay&#8221;.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-step-content \"><img loading=\"lazy\" decoding=\"async\" width=\"689\" height=\"420\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/install-mod-xray-options.jpg\" class=\"attachment-full size-full\" alt=\"\" title=\"\"><p>Potresti scoprire che alcuni dei controlli predefiniti sono di colore ROSSO. Questo significa che sono in conflitto con altri controlli del gioco, che dovrai modificare.<\/p>\n<\/div>\n<\/li>\n<\/ol>\n<\/div>\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Xray-mod-con-Optifine\"><\/span>Xray mod con Optifine<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Il mod Xray (senza Forge) \u00e8 compatibile con Optifine, segui i passi qui sotto per farli funzionare insieme:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Scarica Xray e Optifine per la versione di Minecraft su cui intendi giocare.<\/li>\n\n\n\n<li>Fai doppio clic sul file Jar di Optifine e dovrebbe apparire un popup.<\/li>\n\n\n\n<li>Clicca sul pulsante [Install].<\/li>\n\n\n\n<li>Una nuova finestra pop-up dovrebbe dirti che &#8220;Optifine \u00e8 stato installato con successo&#8221;.<\/li>\n\n\n\n<li>Fai doppio clic a sinistra sul file Jar di Xray. Nella finestra pop-up, clicca sulla piccola freccia verso il basso nell&#8217;elenco a discesa e assicurati che l&#8217;installazione di Optifine sia selezionata.<\/li>\n\n\n\n<li>Clicca su [Install].<\/li>\n\n\n\n<li>Apparir\u00e0 un nuovo pop-up. Assicurati di cliccare su [Create a New Profile], altrimenti Xray potrebbe entrare in conflitto con Optifine.<\/li>\n\n\n\n<li>Nella finestra successiva, scegliete un nome appropriato o mantenete quello predefinito. Clicca su [OK] e un&#8217;altra finestra dovrebbe apparire &#8220;Xray \u00e8 stato installato\/aggiornato con successo&#8221;.<\/li>\n\n\n\n<li>Apri il Minecraft Launcher, assicurati che sia selezionato il profilo Optifine \/ Xray corretto, poi clicca su [Play].<\/li>\n\n\n\n<li>Una volta che il gioco si avvia, puoi controllare che Optifine sia installato cliccando su [Options]&gt; [Video Settings] e nell&#8217;angolo dovrebbe mostrare qualcosa come &#8220;Optifine HD F3 Ultra&#8221;.<\/li>\n\n\n\n<li>Cliccando su [Options]&gt; [Controls] e scorrendo verso il basso, dovresti vedere una sezione chiamata &#8220;Xray&#8221;.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Domande-Risposte-sul-Mod-Xray\"><\/span>Domande \/ Risposte sul Mod Xray<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<ol class=\"rank-math-list \">\n<li id=\"faq-question-1610875473418\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%E2%9D%93-A-cosa-serve-il-mod-Xray\"><\/span>\u2753 A cosa serve il mod Xray?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Questa mod permette di vedere attraverso le texture e trovare il minerale pi\u00f9 facilmente.<\/p>\n\n<\/div>\n<\/li>\n<li id=\"faq-question-1610875479629\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%F0%9F%92%BF-Con-quali-versioni-di-Minecraft-e-compatibile-il-mod-Xray\"><\/span>\ud83d\udcbf Con quali versioni di Minecraft \u00e8 compatibile il mod Xray?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Il pacchetto funziona con le versioni 1.9.4, 1.10.2, 1.11.2, 1.12.2, 1.13.2, 1.14.4, 1.15.2, 1.16.5, 1.17.1, 1.18.2, 1.19.4 e 1.20.2<\/p>\n\n<\/div>\n<\/li>\n<li id=\"faq-question-1610875499970\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"%E2%9A%99%EF%B8%8F-Il-mod-Xray-e-compatibile-con-Forge\"><\/span>\u2699\ufe0f Il mod Xray \u00e8 compatibile con Forge?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Offriamo 2 versioni del mod, una che funziona con Forge e una che funziona senza.<\/p>\n\n<\/div>\n<\/li>\n<\/ol>\n<\/div>\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;5589&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;2&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (2 votes)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Xray Mod Minecraft - 1.7.10 \u2192 1.21.11&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (2 votes)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Xray mod \u00e8 una mod per Minecraft che permette di vedere attraverso i blocchi inutili, come terra, pietra, erba<\/p>\n","protected":false},"author":1,"featured_media":5607,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[105,234,258],"tags":[],"class_list":["post-5589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mod-it","category-1-19","category-1-20","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/5589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/comments?post=5589"}],"version-history":[{"count":27,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/5589\/revisions"}],"predecessor-version":[{"id":22197,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/posts\/5589\/revisions\/22197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/media\/5607"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/media?parent=5589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/categories?post=5589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/it\/wp-json\/wp\/v2\/tags?post=5589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}