{"id":18732,"date":"2023-07-07T09:15:39","date_gmt":"2023-07-07T07:15:39","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=18732"},"modified":"2023-07-07T09:15:43","modified_gmt":"2023-07-07T07:15:43","slug":"composteira-de-minecraft-como-fazer-e-usar","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/pt-br\/composteira-de-minecraft-como-fazer-e-usar\/","title":{"rendered":"Composteira de Minecraft : como fazer e usar ?"},"content":{"rendered":"\n<p>Um <strong>composteira no Minecraft<\/strong> \u00e9 um bloco que transforma certas mat\u00e9rias biol\u00f3gicas e vegetais em p\u00f3 de osso. Ele tamb\u00e9m serve como um bloco de trabalho para os alde\u00f5es<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-1-14-village-and-loot-composter.png\" alt=\"composteira de minecraft\" class=\"wp-image-18688\" width=\"218\" height=\"218\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-1-14-village-and-loot-composter.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-1-14-village-and-loot-composter-150x150.png 150w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><figcaption class=\"wp-element-caption\"><em>Um composteira.<\/em><\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Como fazer uma composteira no Minecraft ?<\/h2>\n\n\n\n<p><strong>Fazer uma composteira<\/strong> n\u00e3o \u00e9 complicado, desde que voc\u00ea tenha os ingredientes certos \u00e0 m\u00e3o. Tudo o que voc\u00ea precisa \u00e9 de 7 placas (de qualquer tipo) dispostas em forma de U.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/craft-composter-minecraft.png\" alt=\"Composteira do Minecraft\" class=\"wp-image-18694\" width=\"417\" height=\"240\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/craft-composter-minecraft.png 647w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/craft-composter-minecraft-300x172.png 300w\" sizes=\"auto, (max-width: 417px) 100vw, 417px\" \/><figcaption class=\"wp-element-caption\"><em>Cria\u00e7\u00e3o de composteira no Minecraft<\/em><\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\">Gera\u00e7\u00e3o natural da composteira<\/h3>\n\n\n\n<p>As composteiras podem ser geradas naturalmente em qualquer fazenda, embora voc\u00ea precise <a href=\"https:\/\/minecraft-tutos.com\/pt-br\/como-posso-encontrar-uma-aldeia-em-minecraft\/\">encontrar uma vila primeiro<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como o composteira funciona no Minecraft ?<\/h2>\n\n\n\n<p>As composteiras reciclam alimentos e mat\u00e9ria vegetal em farinha de ossos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00edvel de preenchimento<\/h3>\n\n\n\n<p>Para fazer isso, o jogador deve usar um dos objetos da composteira. A composteira tem um &#8220;limite&#8221;, cuja altura depende do n\u00edvel de preenchimento.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/composter-minecraft-filled.webp\" alt=\"Composteira cheia do minecraft\" class=\"wp-image-18700\" width=\"212\" height=\"212\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/composter-minecraft-filled.webp 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/composter-minecraft-filled-150x150.webp 150w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><figcaption class=\"wp-element-caption\"><em>Um composteira cheio.<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Quando a composteira est\u00e1 completamente vazia, esse piso fica um pouco acima do bloco abaixo e, quando est\u00e1 completamente cheia, h\u00e1 uma pequena queda no topo. \u00c0 medida que a composteira se enche, todas as unidades dentro dela s\u00e3o empurradas para cima de acordo [<em>somente na vers\u00e3o Bedrock<\/em>].<\/p>\n\n\n\n<p>Visite a Wiki oficial para ver uma lista de todos os ingredientes que voc\u00ea pode colocar em uma composteira : <a href=\"https:\/\/minecraft.fandom.com\/wiki\/Composter#Composting\" target=\"_blank\" rel=\"noreferrer noopener\">Composter on the Minecraft Wiki US<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sistema de compostagem<\/h3>\n\n\n\n<p>O composteira pode ser preenchido com composto adicionando objetos compost\u00e1veis. Uma part\u00edcula verde aparece quando um objeto \u00e9 adicionado com sucesso. Quanto maior for a porcentagem de um objeto, maior ser\u00e1 a probabilidade de outra camada de composto ser adicionada. Cada camada de composto tem a apar\u00eancia de uma vagem. Quando o compostador atinge a s\u00e9tima camada de composto, a apar\u00eancia do composto muda, indicando que a farinha de ossos pode ser coletada usando o compostador uma \u00faltima vez.<\/p>\n\n\n\n<p>Por exemplo, as sementes de trigo t\u00eam 30% de chance de aumentar o n\u00edvel do composteira, o que significa que as sementes de trigo ser\u00e3o consumidas desnecessariamente 70% das vezes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/composter-minecraft-ready.webp\" alt=\"composteira pronto para minecraft\" class=\"wp-image-18706\" width=\"196\" height=\"196\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/composter-minecraft-ready.webp 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/composter-minecraft-ready-150x150.webp 150w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><figcaption class=\"wp-element-caption\"><em>Um composteira pronto com p\u00f3 de osso.<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Peda\u00e7os menores (peda\u00e7os individuais de trigo, fatias de mel\u00e3o etc.) produzir\u00e3o mais composto do que blocos ou outros objetos que possam ser feitos com eles. Os biscoitos s\u00e3o uma exce\u00e7\u00e3o, pois cada receita rende 8 biscoitos e, juntos, eles produzem mais de 3 vezes mais composto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mudan\u00e7a de emprego<\/h3>\n\n\n\n<p>Se uma aldeia tiver um composteira que n\u00e3o tenha sido reivindicado por um alde\u00e3o, qualquer alde\u00e3o que ainda n\u00e3o tenha escolhido um bloco de tarefas ter\u00e1 a chance de <a href=\"https:\/\/minecraft-tutos.com\/pt-br\/como-se-da-a-um-aldeao-um-emprego-em-minecraft\/\">mudar de profiss\u00e3o<\/a> para agricultor.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Pedra vermelha<\/h4>\n\n\n\n<p>Um composteira pode servir como fonte de energia de redstone para um comparador de redstone. Com uma composteira atr\u00e1s dele (diretamente ou separada por um bloco s\u00f3lido sem energia), um comparador emite um sinal de intensidade entre 0 e 8, proporcional ao n\u00edvel de enchimento da composteira : 0 para vazio, 1 para 1\u20447 cheio, 2 para 2\u20447 cheio e assim por diante at\u00e9 6. 7 corresponde a completamente cheio, mas o p\u00f3 de osso n\u00e3o est\u00e1 pronto para ser coletado, e 8 a completamente cheio e o p\u00f3 de osso est\u00e1 pronto para ser coletado. Entretanto, se houver um bloqueio entre o compostor e o comparador, o comparador n\u00e3o ser\u00e1 atualizado imediatamente.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Funis<\/h4>\n\n\n\n<p>Os compostores podem interagir com funis. Um funil localizado diretamente sob um compostor extrai farinha de ossos dele. Um funil ou conta-gotas voltado para baixo, diretamente acima de um compostor, empurra objetos para dentro dele.<\/p>\n\n\n\n<p>Os funis n\u00e3o podem interagir com os cantos de uma composteira.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;18732&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;2&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.5 \\\/ 5 - (2 votos)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Composteira de Minecraft : como fazer e usar ?&quot;,&quot;width&quot;:&quot;106&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 106px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            4.5 \/ 5 - (2 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um composteira no Minecraft \u00e9 um bloco que transforma certas mat\u00e9rias biol\u00f3gicas e vegetais em p\u00f3 de osso. Ele tamb\u00e9m<\/p>\n","protected":false},"author":2,"featured_media":18722,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-18732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-como","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/18732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/comments?post=18732"}],"version-history":[{"count":9,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/18732\/revisions"}],"predecessor-version":[{"id":18829,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/18732\/revisions\/18829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media\/18722"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media?parent=18732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/categories?post=18732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/tags?post=18732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}