{"id":18836,"date":"2023-07-07T20:23:12","date_gmt":"2023-07-07T18:23:12","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=18836"},"modified":"2023-07-07T20:23:16","modified_gmt":"2023-07-07T18:23:16","slug":"sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/pt-br\/sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador\/","title":{"rendered":"Sinalizador do Minecraft : como criar e ativar um sinalizador"},"content":{"rendered":"\n<p>Os <strong>sinalizadores do Minecraft<\/strong> s\u00e3o itens muito \u00fateis, geralmente obtidos bem no final do jogo. Eles t\u00eam a vantagem de atuar n\u00e3o apenas como marcadores de localiza\u00e7\u00e3o que podem ser vistos de muito longe, mas tamb\u00e9m proporcionam um poderoso efeito de status em uma \u00e1rea espec\u00edfica. Por esse motivo, os beacons s\u00e3o um dos blocos raros mais populares do jogo, apesar do tempo necess\u00e1rio para obt\u00ea-los.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/beacon-minecraft.png\" alt=\"sinalizador do minecraft\" class=\"wp-image-18747\" width=\"250\" height=\"250\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/beacon-minecraft.png 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/beacon-minecraft-150x150.png 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><figcaption class=\"wp-element-caption\"><em>Um farol no Minecraft<\/em><\/figcaption><\/figure><\/div>\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sum\u00e1rio<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a989bee6ac8e\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a989bee6ac8e\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/minecraft-tutos.com\/pt-br\/sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador\/#Como-construir-um-farol-no-Minecraft\" >Como construir um farol no Minecraft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/minecraft-tutos.com\/pt-br\/sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador\/#Como-fazer-uma-piramide-para-a-tag\" >Como fazer uma pir\u00e2mide para a tag<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/minecraft-tutos.com\/pt-br\/sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador\/#Como-ativar-um-sinalizador-no-Minecraft\" >Como ativar um sinalizador no Minecraft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/minecraft-tutos.com\/pt-br\/sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador\/#Alcance-do-sinalizador-no-Minecraft\" >Alcance do sinalizador no Minecraft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/minecraft-tutos.com\/pt-br\/sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador\/#Quais-sao-os-efeitos-de-status-do-beacon\" >Quais s\u00e3o os efeitos de status do beacon ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/minecraft-tutos.com\/pt-br\/sinalizador-do-minecraft-como-criar-e-ativar-um-sinalizador\/#Como-alterar-a-cor-dos-sinalizadores-no-Minecraft\" >Como alterar a cor dos sinalizadores no Minecraft<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como-construir-um-farol-no-Minecraft\"><\/span>Como construir um farol no Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Para construir um farol no Minecraft<\/strong>, voc\u00ea precisa coletar 5 blocos de vidro, 3 blocos de obsidiana e uma estrela do Nether. O vidro e a obsidiana s\u00e3o relativamente f\u00e1ceis de obter : derreta areia em um forno para obter o vidro e despeje um balde de \u00e1gua sobre a lava para obter a obsidiana. N\u00e3o se esque\u00e7a de que voc\u00ea precisa de uma picareta de diamante ou netherita para extrair a obsidiana.<\/p>\n\n\n\n<p>Para obter uma Nether Star, voc\u00ea deve derrotar o Wither. Quando voc\u00ea matar o Wither, ele deixar\u00e1 cair uma Nether Star, que s\u00f3 poder\u00e1 ser usada para fazer o sinalizador.<\/p>\n\n\n\n<p><strong>Para fazer um sinalizador no Minecraft<\/strong>, voc\u00ea precisa combinar esses ingredientes na seguinte ordem :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/craft-beacon-minecraft.jpeg\" alt=\"etiqueta de artesanato do minecraft\" class=\"wp-image-18753\" width=\"446\" height=\"256\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/craft-beacon-minecraft.jpeg 540w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/craft-beacon-minecraft-300x172.jpeg 300w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><figcaption class=\"wp-element-caption\"><em>Criando um sinalizador no Minecraft<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Entretanto, voc\u00ea n\u00e3o pode simplesmente coloc\u00e1-la no ch\u00e3o e us\u00e1-la. Primeiro, voc\u00ea precisa construir uma pir\u00e2mide, que \u00e9 a primeira etapa para ativar a tag.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como-fazer-uma-piramide-para-a-tag\"><\/span>Como fazer uma pir\u00e2mide para a tag<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O bloco do sinalizador por si s\u00f3 n\u00e3o \u00e9 suficiente para funcionar sozinho. Para funcionar, o sinalizador deve ser colocado sobre uma funda\u00e7\u00e3o ou base em forma de pir\u00e2mide feita inteiramente de blocos minerais. O bloco do sinalizador tamb\u00e9m deve ter acesso ao c\u00e9u, independentemente da profundidade em que for colocado.<\/p>\n\n\n\n<p>Para atingir a pot\u00eancia m\u00e1xima do sinalizador, o ideal \u00e9 que o jogador tenha constru\u00eddo quatro n\u00edveis, com o sinalizador posicionado no topo, no bloco central de uma \u00e1rea 3\u00d73, que \u00e9 a camada superior da base do sinalizador.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"623\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/pyramid-beacon-activation-minecraft.jpeg\" alt=\"pir\u00e2mide de farol do minecraft\" class=\"wp-image-18760\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/pyramid-beacon-activation-minecraft.jpeg 1000w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/pyramid-beacon-activation-minecraft-300x187.jpeg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/pyramid-beacon-activation-minecraft-768x478.jpeg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>Pir\u00e2mides para o sinalizador no Minecraft baseadas em blocos de diamante. Fonte : <a href=\"https:\/\/minecraft.fandom.com\/wiki\/Beacon\" target=\"_blank\" rel=\"noreferrer noopener\">Minecraft Wiki<\/a><\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Todos os minerais s\u00e3o adequados para a base, com exce\u00e7\u00e3o de redstone e quartzo. Netherita, diamantes, ouro, ferro e esmeraldas, quando processados em blocos, s\u00e3o op\u00e7\u00f5es v\u00e1lidas e tamb\u00e9m podem ser misturados. Entretanto, dada a utilidade dos diamantes, do ouro e das esmeraldas para o com\u00e9rcio e a fabrica\u00e7\u00e3o de equipamentos, \u00e9 aconselh\u00e1vel usar apenas blocos de ferro, que s\u00e3o o investimento mais barato.<\/p>\n\n\n\n<p>Para uma pir\u00e2mide completa de quatro camadas, veja a seguir o tamanho de cada camada, os poderes dispon\u00edveis e a variedade de blocos para cada variante :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>4\u00aa camada: tamanho do bloco 9\u00d79, todos os poderes prim\u00e1rios e secund\u00e1rios dispon\u00edveis, alcance m\u00e1ximo de 50.<\/li>\n\n\n\n<li>3\u00aa camada: tamanho do bloco 7\u00d77, todos os poderes prim\u00e1rios dispon\u00edveis, alcance m\u00e1ximo de 40.<\/li>\n\n\n\n<li>2\u00aa camada: blocos de tamanho 5\u00d75, somente os poderes Haste, Speed, Jump Acceleration e Resistance est\u00e3o dispon\u00edveis, com alcance m\u00e1ximo de 30.<\/li>\n\n\n\n<li>1\u00aa camada : Blocos grandes de 3\u00d73, somente Haste e Velocidade dispon\u00edveis, alcance m\u00e1ximo de 20.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como-ativar-um-sinalizador-no-Minecraft\"><\/span>Como ativar um sinalizador no Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Quando voc\u00ea coloca o sinalizador no topo da pir\u00e2mide, ele se acende. No entanto, voc\u00ea n\u00e3o obter\u00e1 nenhum efeito de status imediatamente. H\u00e1 outra etapa que voc\u00ea precisa concluir primeiro.<\/p>\n\n\n\n<p>Interaja com a etiqueta para abrir seu menu. Ele lista todos os efeitos de status que voc\u00ea pode ativar. Selecione um poder prim\u00e1rio (e um poder secund\u00e1rio se voc\u00ea tiver uma pir\u00e2mide de 4 n\u00edveis). Em seguida, insira um lingote de Netherita, uma esmeralda, um diamante, um lingote de ouro ou um lingote de ferro. Quando voc\u00ea inserir um desses itens, ele permitir\u00e1 que voc\u00ea pressione o bot\u00e3o de acionamento e ative totalmente o sinalizador.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Alcance-do-sinalizador-no-Minecraft\"><\/span>Alcance do sinalizador no Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O sinalizador afeta uma \u00e1rea na forma de uma coluna quadrada, estendendo-se para baixo e para ambos os lados em um \u00e2ngulo determinado pelo tamanho da base da pir\u00e2mide e para cima em uma dist\u00e2ncia desse \u00e2ngulo + 384 blocos.<\/p>\n\n\n\n<p>O alcance do efeito do sinalizador \u00e9 limitado pela dist\u00e2ncia da simula\u00e7\u00e3o. Portanto, em uma dist\u00e2ncia de simula\u00e7\u00e3o de 4 com uma pir\u00e2mide de n\u00edvel 4, o efeito n\u00e3o alcan\u00e7ar\u00e1 os punks nos cantos do alcance do sinalizador.<\/p>\n\n\n\n<p>A dist\u00e2ncia entre o jogador e o bloco do sinalizador n\u00e3o afeta a intensidade do efeito de estado.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Tamanho da pir\u00e2mide<\/td><td>Alcance do efeito<br>(blocos)<\/td><td>Dura\u00e7\u00e3o do efeito<br>(segundos)<\/td><\/tr><tr><td>1 n\u00edvel<\/td><td>20<\/td><td>11<\/td><\/tr><tr><td>2 n\u00edveis<\/td><td>30<\/td><td>13<\/td><\/tr><tr><td>3 n\u00edveis<\/td><td>40<\/td><td>15<\/td><\/tr><tr><td>4 n\u00edveis<\/td><td>50<\/td><td>17<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-beacon-scope.jpeg\" alt=\"alcance do sinalizador do minecraft\" class=\"wp-image-18766\" width=\"870\" height=\"521\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-beacon-scope.jpeg 1000w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-beacon-scope-300x180.jpeg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-beacon-scope-768x461.jpeg 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><figcaption class=\"wp-element-caption\"><em>Alcance dos 4 n\u00edveis de sinalizadores no Minecraft<\/em><\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quais-sao-os-efeitos-de-status-do-beacon\"><\/span>Quais s\u00e3o os efeitos de status do beacon ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ao ativar a tag, voc\u00ea pode optar por ganhar um efeito de status. H\u00e1 5 poderes prim\u00e1rios dispon\u00edveis, todos os quais o aproximam de um super-her\u00f3i do Minecraft :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Velocidade<\/li>\n\n\n\n<li>Resist\u00eancia<\/li>\n\n\n\n<li>Saltos aprimorados<\/li>\n\n\n\n<li>For\u00e7a<\/li>\n<\/ul>\n\n\n\n<p>Speed e Speed est\u00e3o dispon\u00edveis se voc\u00ea construir uma pir\u00e2mide de n\u00edvel \u00fanico. Para desbloquear a resist\u00eancia e os saltos aprimorados, voc\u00ea precisa construir uma pir\u00e2mide de pelo menos dois n\u00edveis. Para obter o efeito de status Strength (For\u00e7a), voc\u00ea deve construir uma pir\u00e2mide de 3 n\u00edveis. Todos esses efeitos de status s\u00e3o de n\u00edvel 1.<\/p>\n\n\n\n<p>Para definir os poderes da tag, basta clicar com o bot\u00e3o direito do mouse sobre ela para abrir a interface. Para come\u00e7ar a us\u00e1-la, voc\u00ea precisa dar a ela um lingote de Netherita, uma esmeralda, um diamante, um lingote de ouro ou um lingote de ferro. Isso tamb\u00e9m deve ser feito toda vez que os efeitos de estado forem modificados :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-beacon-interface.jpeg\" alt=\"interface de tag do minecraft\" class=\"wp-image-18772\" width=\"356\" height=\"339\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-beacon-interface.jpeg 460w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/minecraft-beacon-interface-300x286.jpeg 300w\" sizes=\"auto, (max-width: 356px) 100vw, 356px\" \/><figcaption class=\"wp-element-caption\"><em>Interface de beacon ativada<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Se estiver construindo uma pir\u00e2mide de quatro camadas, voc\u00ea pode escolher um poder prim\u00e1rio e um secund\u00e1rio. Para o poder secund\u00e1rio, voc\u00ea pode optar por ter Regenera\u00e7\u00e3o no n\u00edvel 1 ou aumentar o poder prim\u00e1rio para o n\u00edvel 2.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como-alterar-a-cor-dos-sinalizadores-no-Minecraft\"><\/span>Como alterar a cor dos sinalizadores no Minecraft<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Quando voc\u00ea ativa um sinalizador, ele emite um feixe que pode ser usado para marcar locais importantes. No entanto, se voc\u00ea quiser usar v\u00e1rios sinalizadores para diferentes \u00e1reas, talvez queira fazer com que os feixes tenham cores diferentes.<\/p>\n\n\n\n<p>Para alterar a cor de um feixe, voc\u00ea precisa colocar um vidro colorido sobre ele. Por exemplo, para tornar o feixe azul, coloque um bloco de vidro colorido azul sobre o farol.<\/p>\n\n\n\n<p>Para obter vidro colorido de uma determinada cor, voc\u00ea precisa obter a colora\u00e7\u00e3o da cor desejada e 8 blocos de vidro. Em seguida, coloque-os na tabela de fabrica\u00e7\u00e3o na seguinte ordem :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"310\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/glass-tint-minecraft-beacon.jpeg\" alt=\"mudar a cor do feixe do farol no minecraft\" class=\"wp-image-18778\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/glass-tint-minecraft-beacon.jpeg 540w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/glass-tint-minecraft-beacon-300x172.jpeg 300w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\"><em>A embarca\u00e7\u00e3o de vidro colorido a ser usada para alterar a cor do feixe do farol<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>Voc\u00ea pode misturar as cores para obter tonalidades diferentes, colocando v\u00e1rios blocos de vidro colorido no farol. Por exemplo, voc\u00ea pode colocar um bloco de vidro com tonalidade laranja e um bloco de vidro com tonalidade rosa no farol para que o feixe fique com uma cor rosa quente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/color-spectrum-beacon-minecraft-1.jpeg\" alt=\"espectro de cores do farol minecraft\" class=\"wp-image-18790\" width=\"580\" height=\"435\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/color-spectrum-beacon-minecraft-1.jpeg 1000w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/color-spectrum-beacon-minecraft-1-300x225.jpeg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2023\/07\/color-spectrum-beacon-minecraft-1-768x576.jpeg 768w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption class=\"wp-element-caption\"><em>Espectro de cores do farol<\/em><\/figcaption><\/figure><\/div>\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;18836&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5 \\\/ 5 - (1 voto)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Sinalizador do Minecraft : como criar e ativar um sinalizador&quot;,&quot;width&quot;:&quot;118&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 118px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5 \/ 5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Os sinalizadores do Minecraft s\u00e3o itens muito \u00fateis, geralmente obtidos bem no final do jogo. Eles t\u00eam a vantagem de<\/p>\n","protected":false},"author":2,"featured_media":18806,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-18836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-como","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/18836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/comments?post=18836"}],"version-history":[{"count":2,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/18836\/revisions"}],"predecessor-version":[{"id":18852,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/18836\/revisions\/18852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media\/18806"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media?parent=18836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/categories?post=18836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/tags?post=18836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}