{"id":2200,"date":"2021-01-23T14:05:49","date_gmt":"2021-01-23T13:05:49","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=2200"},"modified":"2021-01-23T14:05:50","modified_gmt":"2021-01-23T13:05:50","slug":"o-minecraft-seed-na-origem-de-herobrine-foi-descoberto","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/pt-br\/o-minecraft-seed-na-origem-de-herobrine-foi-descoberto\/","title":{"rendered":"O Minecraft Seed na origem de Herobrine foi descoberto !"},"content":{"rendered":"\n<p>Herobrine \u00e9 certamente um dos mitos mais populares no mundo do Minecraft, este car\u00e1ter m\u00edstico, estranho e perturbador parece estar \u00e0 espreita em nossos mundos h\u00e1 anos.<\/p>\n\n\n\n<p>Estamos aqui hoje para falar sobre a descoberta da seed na qual ele foi visto pela primeira vez. Foi o coletivo Minecraft@home que conseguiu encontr\u00e1-la. Eles n\u00e3o est\u00e3o em sua primeira tentativa porque tamb\u00e9m compartilharam a descoberta do seed do pacote de textura padr\u00e3o, bem como o seed da tela inicial da Minecraft original.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/herobrine-in-minecraft.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/herobrine-in-minecraft.jpg\" alt=\"The first appearance of Herobrine in the Alpha version of Minecraft\" class=\"wp-image-2183\" width=\"722\" height=\"405\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/herobrine-in-minecraft.jpg 850w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/herobrine-in-minecraft-300x168.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/herobrine-in-minecraft-768x431.jpg 768w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/a><figcaption>A primeira apari\u00e7\u00e3o do Herobrine na vers\u00e3o alfa do Minecraft<\/figcaption><\/figure><\/div>\n\n\n\n<p>Se voc\u00ea est\u00e1 pronto para estar no seed Herobrine, aqui est\u00e3o as informa\u00e7\u00f5es necess\u00e1rias e informa\u00e7\u00f5es de contato :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>As coordenadas: X=5,06 Y=71 (72,62 olho pos) Z=-298,54<\/li><li>Semente : 478868574074082066804<\/li><li>Vers\u00e3o do Minecraft: Java Alfa 1.0.16_02<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Tutorial &#8211; Como carregar o seed Herobrine em Minecraft Alpha<\/h2>\n\n\n\n<p>Certifique-se de estar usando a Minecraft Java Edition, com o &#8220;Version History&#8221; ativado no lan\u00e7ador, e escolha a vers\u00e3o a1.0.16. Esta vers\u00e3o n\u00e3o suporta a entrada de seed, portanto voc\u00ea ter\u00e1 que usar a edi\u00e7\u00e3o de arquivo de backup, ou simplesmente usar <a class=\"rank-math-link\" href=\"https:\/\/files.mcatho.me\/herobrine\/World1.zip\" target=\"_blank\" rel=\"noopener\">este arquivo mundial j\u00e1 preparado<\/a>.<\/p>\n\n\n\n<p>Isto ir\u00e1 gerar uma nova vers\u00e3o do mundo herobrine e voc\u00ea estar\u00e1 nas coordenadas exatas. Certifique-se de que voc\u00ea est\u00e1 usando a vers\u00e3o correta do Minecraft ou ele n\u00e3o funcionar\u00e1.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The original Herobrine seed has finally been found!\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/8OrGlG2hON0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobirne-view-up.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobirne-view-up.jpg\" alt=\"\" data-id=\"2187\" data-full-url=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobirne-view-up.jpg\" data-link=\"https:\/\/minecraft-tutos.com\/?attachment_id=2187#main\" class=\"wp-image-2187\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobirne-view-up.jpg 960w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobirne-view-up-300x169.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobirne-view-up-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobrine-up.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobrine-up.jpg\" alt=\"\" data-id=\"2191\" data-full-url=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobrine-up.jpg\" data-link=\"https:\/\/minecraft-tutos.com\/?attachment_id=2191#main\" class=\"wp-image-2191\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobrine-up.jpg 960w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobrine-up-300x169.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/01\/seed-minecraft-herobrine-up-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Para saber mais sobre como eles fizeram para descobrir este SEED, deixei que voc\u00ea <a class=\"rank-math-link\" href=\"https:\/\/docs.google.com\/document\/d\/e\/2PACX-1vQw1gw3ITldVWrZv7FhGTVfQkn1ixROE1V7wNojCN6vXfoO_3ikpSnxA634hTjyXvGIzP5jQn_TqlcB\/pub\" target=\"_blank\" rel=\"noopener\">consultasse a metodologia<\/a> deles (bastante complexa!).<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;2200&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;11&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.3&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.3 \\\/ 5 - (11 votos)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;O Minecraft Seed na origem de Herobrine foi descoberto !&quot;,&quot;width&quot;:&quot;101.2&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 101.2px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            4.3 \/ 5 - (11 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Herobrine \u00e9 certamente um dos mitos mais populares no mundo do Minecraft, este car\u00e1ter m\u00edstico, estranho e perturbador parece estar<\/p>\n","protected":false},"author":1,"featured_media":2181,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[44],"tags":[],"class_list":["post-2200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/2200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/comments?post=2200"}],"version-history":[{"count":2,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/2200\/revisions"}],"predecessor-version":[{"id":2202,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/2200\/revisions\/2202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media\/2181"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/categories?post=2200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/tags?post=2200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}