{"id":8462,"date":"2023-07-05T12:02:00","date_gmt":"2023-07-05T10:02:00","guid":{"rendered":"https:\/\/minecraft-tutos.com\/?p=8462"},"modified":"2023-10-08T09:23:25","modified_gmt":"2023-10-08T07:23:25","slug":"skyblock-map-minecraft","status":"publish","type":"post","link":"https:\/\/minecraft-tutos.com\/pt-br\/skyblock-map-minecraft\/","title":{"rendered":"Skyblock &#8211; Map Minecraft &#8211; 1.10.2 \u2192 1.20.2"},"content":{"rendered":"\n<p>Todos voc\u00eas conhecem o conceito do <strong>ma Skyblock<\/strong>, ele j\u00e1 foi visitado e revisitado de todos os \u00e2ngulos. Com o Skyblock 4, Astavie, o autor do mapa, quis voltar \u00e0s origens do Skyblock, acrescentando mais objetivos e um final ao mapa.<\/p>\n\n\n\n<p>Aqui est\u00e3o as caracter\u00edsticas deste map da Minecraft Skyblock:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Verruga do Vazio est\u00e1 dispon\u00edvel<\/li>\n\n\n\n<li>Voc\u00ea pode ir at\u00e9 o fim<\/li>\n\n\n\n<li>10 novos desafios!<\/li>\n\n\n\n<li>V\u00e1rios mini-islandas com itens adicionais<\/li>\n\n\n\n<li>Os zumbis t\u00eam a chance de deixar cair cascalho<\/li>\n\n\n\n<li>As brasas t\u00eam a chance de jogar quartzo da rede<\/li>\n\n\n\n<li>Os zumbis mumificados t\u00eam a chance de jogar quartzo<\/li>\n\n\n\n<li>Os esqueletos t\u00eam a chance de jogar areia na alma<\/li>\n\n\n\n<li>H\u00e1 uma fronteira de -1000 a 1000 no mundo e nos Pa\u00edses Baixos.<\/li>\n\n\n\n<li>Tem progresso personalizado em 1.12+.<\/li>\n\n\n\n<li>Quando todos est\u00e3o no Fim, o comando da fronteira mundial \u00e9 reiniciado (apenas 1.12+)<\/li>\n\n\n\n<li>Quando algu\u00e9m deixa o Fim, a fronteira volta, portanto tenha cuidado (apenas 1,12+)<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"523\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-minecraft-1024x523.jpg\" alt=\"Uma ilha no mapa do Skyblock\" class=\"wp-image-8444\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-minecraft-1024x523.jpg 1024w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-minecraft-300x153.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-minecraft-768x392.jpg 768w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-minecraft.jpg 1351w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Uma ilha no mapa do Skyblock<\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">As regras<\/h2>\n\n\n\n<p>H\u00e1 2 regras que voc\u00ea deve respeitar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>N\u00e3o salte deliberadamente da ilha para regenerar sua sa\u00fade<\/li>\n\n\n\n<li>Jogue pelo menos com dificuldade f\u00e1cil<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Os desafios<\/h2>\n\n\n\n<p>Voc\u00ea encontrar\u00e1 abaixo uma lista de desafios a serem alcan\u00e7ados para o map do Skyblock 4, tentar alcan\u00e7\u00e1-los a todos n\u00e3o ser\u00e1 t\u00e3o f\u00e1cil:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Construir um gerador de paralelep\u00edpedos<\/li>\n\n\n\n<li>Construir uma casa<\/li>\n\n\n\n<li>Expandir a ilha<\/li>\n\n\n\n<li>Fazer uma fazenda de mel\u00e3o<\/li>\n\n\n\n<li>Fazer uma fazenda de ab\u00f3boras<\/li>\n\n\n\n<li>Fazer um canavial \/ fazenda de cana de a\u00e7\u00facar<\/li>\n\n\n\n<li>Fazer uma fazenda de trigo<\/li>\n\n\n\n<li>Fazer um cogumelo vermelho gigante<\/li>\n\n\n\n<li>Fa\u00e7a uma cama<\/li>\n\n\n\n<li>Fazer 64 tijolos de pedra<\/li>\n\n\n\n<li>Fazer 20 tochas<\/li>\n\n\n\n<li>Fazer uma fonte de \u00e1gua infinita<\/li>\n\n\n\n<li>Fazer um forno<\/li>\n\n\n\n<li>Fazer um pequeno lago<\/li>\n\n\n\n<li>Construir uma plataforma a 24 quarteir\u00f5es da ilha, para que as multid\u00f5es possam aparecer<\/li>\n\n\n\n<li>Fazer 10 cactos de corante verde<\/li>\n\n\n\n<li>Fazer 10 cogumelos guisados<\/li>\n\n\n\n<li>Fa\u00e7a 10 Lanternas Jack &#8216;o&#8217; Lanternas<\/li>\n\n\n\n<li>Fazer 10 estantes<\/li>\n\n\n\n<li>Fazer 10 p\u00e3es<\/li>\n\n\n\n<li>Recolher 10 contas finais<\/li>\n\n\n\n<li>Cozinhar 10 peixes<\/li>\n\n\n\n<li>Fazer 10 l\u00e3s pretas<\/li>\n\n\n\n<li>Fazer 10 l\u00e3s cinzas<\/li>\n\n\n\n<li>Fa\u00e7a 10 L\u00e3s Cinzas Claras<\/li>\n\n\n\n<li>Fa\u00e7a 10 L\u00e3s de Lim\u00e3o Verde<\/li>\n\n\n\n<li>Fazer 10 l\u00e3s vermelhas<\/li>\n\n\n\n<li>Fazer 10 l\u00e3s amarelas<\/li>\n\n\n\n<li>Fazer 10 l\u00e3s rosas<\/li>\n\n\n\n<li>Fa\u00e7a 10 L\u00e3s Verdes<\/li>\n\n\n\n<li>Fa\u00e7a 10 L\u00e3s Laranjas<\/li>\n\n\n\n<li>Fa\u00e7a 10 Golems de Neve<\/li>\n\n\n\n<li>Fazer 20 pinturas<\/li>\n\n\n\n<li>Construir e iluminar um portal Nether<\/li>\n\n\n\n<li>Fazer 5 barras de ouro<\/li>\n\n\n\n<li>Fazer 16 pain\u00e9is de vidro<\/li>\n\n\n\n<li>Coletar 50 troncos de b\u00e9tula<\/li>\n\n\n\n<li>Colete 64 setas e fa\u00e7a um arco<\/li>\n\n\n\n<li>Fa\u00e7a 10 bot\u00f5es de pedra<\/li>\n\n\n\n<li>Fazer 30 lajes de pedra<\/li>\n\n\n\n<li>Fazer 10 sinais<\/li>\n\n\n\n<li>Fa\u00e7a 20 escadas<\/li>\n\n\n\n<li>Fazer 20 cercas<\/li>\n\n\n\n<li>Fazer 20 port\u00f5es de cerca<\/li>\n\n\n\n<li>Fa\u00e7a 10 alavancas<\/li>\n\n\n\n<li>Fazer 10 al\u00e7ap\u00f5es<\/li>\n\n\n\n<li>Fazer 10 placas de press\u00e3o de pedra<\/li>\n\n\n\n<li>Fazer 10 placas de press\u00e3o de madeira<\/li>\n\n\n\n<li>Recolher 64 p\u00f3s de ossos<\/li>\n\n\n\n<li>Fazer 20 escadas de paralelep\u00edpedos<\/li>\n\n\n\n<li>Recolher 64 ferro<\/li>\n\n\n\n<li>Fazer uma fazenda de ouro na parte inferior<\/li>\n\n\n\n<li>Curar um alde\u00e3o zumbi<\/li>\n\n\n\n<li><a href=\"https:\/\/minecraft-tutos.com\/pt-br\/minecraft-golem-de-ferro-como-fazer-onde-encontra-los-o-que-eles-fazem\/\">Fazer aparecer um golem de ferro<\/a><\/li>\n\n\n\n<li>Use Redstone para 3 m\u00e1quinas<\/li>\n\n\n\n<li>Encontre um peda\u00e7o de baba e crie uma fazenda de baba<\/li>\n\n\n\n<li>Fazer um sistema de aqueduto de lava<\/li>\n\n\n\n<li>V\u00e1 at\u00e9 o fim e derrote o Drag\u00e3o<\/li>\n\n\n\n<li>Encontre um elytra<\/li>\n\n\n\n<li>Fazer o Wither aparecer e derrot\u00e1-lo<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"400\" src=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-map.jpg\" alt=\"alone skyblock\" class=\"wp-image-8451\" title=\"\" srcset=\"https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-map.jpg 875w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-map-300x137.jpg 300w, https:\/\/minecraft-tutos.com\/wp-content\/uploads\/2021\/11\/skyblock-map-768x351.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><figcaption class=\"wp-element-caption\">Voc\u00ea n\u00e3o se sente muito solit\u00e1rio em sua ilha?<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Baixe<\/h2>\n\n\n\n<p>Escolha a vers\u00e3o do mapa de acordo com sua vers\u00e3o de Minecraft. Recomendamos que voc\u00ea utilize a vers\u00e3o mais recente para desfrutar de todas as caracter\u00edsticas do Skyblock 3 e 4. Para as vers\u00f5es mais recentes, 1.15.2, 1.16.5, 1.17.1. 1.18.2 e 1.19.4, os links para download s\u00e3o os do mapa &#8220;Vanilla Skyblock&#8221; porque o conceito \u00e9 o mesmo.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/legacy.curseforge.com\/minecraft\/worlds\/skyblock-classic-edition\/download\/4775973\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Skyblock Classic [1.20.2]<\/a>\u00a0\/<a href=\"https:\/\/legacy.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/4785053\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Vanilla Skyblock [1.20.2]<\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/3957961\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/skyblock-classic-edition\/download\/4329110\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/skyblock-classic-edition\/download\/4329110\" target=\"_blank\" rel=\"noopener\"><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/skyblock-classic-edition\/download\/4440858\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Skyblock Classic [1.19.4]<\/a>&nbsp;\/<a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/3957961\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Vanilla Skyblock [1.19.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/skyblock-classic-edition\/download\/3921124\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Skyblock Classic [1.18.2]<\/a> \/ <a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/skyblock-advanced\/download\/3639238\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Skyblock Advanced [1.18.1]<\/a> \/ <a href=\"https:\/\/www.mediafire.com\/file\/tpvsn66bu72book\/Skyblock_4.10.zip\/file\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Skyblock 4 [1.18]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/3381739\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Vanilla Skyblock [1.17.1]<\/a> \/ <a href=\"https:\/\/www.mediafire.com\/file\/c663pmigtrkppqs\/Skyblock_4.09.1.zip\/file\" target=\"_blank\" rel=\"noreferrer noopener\">Skyblock 4 [1.17.1]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/2990269\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Vanilla Skyblock [1.16.5]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/2820319\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Vanilla Skyblock [1.15.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/2765575\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Vanilla Skyblock [1.14.4]<\/a> \/ <a href=\"https:\/\/www.curseforge.com\/minecraft\/worlds\/vanilla-skyblock\/download\/2765575\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83d\udce5 Skyblock 4 [1.14.4]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/minecraft.curseforge.com\/projects\/skyblock-3\/files\/2455897\/download\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Skyblock 3 [1.12.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/minecraft.curseforge.com\/projects\/skyblock-3\/files\/2329522\/download\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Skyblock 3 [1.11.2]<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/minecraft.curseforge.com\/projects\/skyblock-3\/files\/2325186\/download\" target=\"_blank\" rel=\"noopener\">\ud83d\udce5 Skyblock 3 [1.10.2]<\/a><\/li>\n<\/ul>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;8462&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;4&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.7 \\\/ 5 - (4 votos)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Skyblock - Map Minecraft - 1.10.2 \u2192 1.20.2&quot;,&quot;width&quot;:&quot;110.8&quot;,&quot;_legend&quot;:&quot;{score} \\\/ {best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 110.8px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            4.7 \/ 5 - (4 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Todos voc\u00eas conhecem o conceito do ma Skyblock, ele j\u00e1 foi visitado e revisitado de todos os \u00e2ngulos. Com o<\/p>\n","protected":false},"author":1,"featured_media":8441,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[96],"tags":[],"class_list":["post-8462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-map-pt-br","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"_links":{"self":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/8462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/comments?post=8462"}],"version-history":[{"count":14,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/8462\/revisions"}],"predecessor-version":[{"id":19634,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/posts\/8462\/revisions\/19634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media\/8441"}],"wp:attachment":[{"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/media?parent=8462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/categories?post=8462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minecraft-tutos.com\/pt-br\/wp-json\/wp\/v2\/tags?post=8462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}